{"id":44594,"date":"2026-09-01T22:53:41","date_gmt":"2026-09-02T05:53:41","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=44594"},"modified":"2026-09-01T22:53:42","modified_gmt":"2026-09-02T05:53:42","slug":"cierran-fuerte-en-la-4t-pero-falta-la-encuesta","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2026\/09\/01\/cierran-fuerte-en-la-4t-pero-falta-la-encuesta\/","title":{"rendered":"Cierran fuerte en la 4T: pero falta la encuesta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Columna El Zancudo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arturo Soto Mungu\u00eda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cierran fuerte en la 4T: pero falta la encuesta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lunes 31 de agosto de 2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Paulina Oca\u00f1a: clave para destrabar conflicto de Covafam<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A tambor batiente cerraron las asambleas informativas de los seis aspirantes de Morena a la CDTYSN (abreviatura muy \u00fatil para ahorrarnos el eufemismo con el que se alude a la precandidatura al gobierno del estado, o sea el Comit\u00e9 de Defensa de la Transformaci\u00f3n y la Soberan\u00eda Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Y si de la convocatoria en este cierre dependiera tal precandidatura, la que se llevar\u00eda las palmas ser\u00eda C\u00e9lida L\u00f3pez, que ayer reuni\u00f3 a m\u00e1s de ocho mil personas en el Expo F\u00f3rum de Hermosillo, articulando un discurso de reconocimiento al trabajo del gobernador Alfonso Durazo y de la presidenta Claudia Sheinbaum, y reivindicando la necesidad de darle continuidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Se manifest\u00f3 segura de ganar la encuesta que habr\u00e1 de aplicar en estos d\u00edas la Comisi\u00f3n Nacional de Elecciones y se pronunci\u00f3 por sumar a todos en esas tareas: \u201cPase lo que pase en la encuesta, nunca me ir\u00e9 de este movimiento, aqu\u00ed seguir\u00e9 trabajando, defendiendo la transformaci\u00f3n y caminando junto al pueblo\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Es posible que este haya sido el evento masivo m\u00e1s grande que tuvo C\u00e9lida en este proceso, aunque hay que apuntar que en varias ocasiones, enlaz\u00f3 a miles de usuarios de las redes sociales en transmisiones en vivo, una modalidad que aport\u00f3 la parte innovadora en esta justa. Al modo C\u00e9lida, no desaprovech\u00f3 la oportunidad para reconocer el trabajo de los otros aspirantes, a quienes manifest\u00f3 su respeto, pero (siempre hay un pero) les va a ganar en la encuesta, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Desde luego que los aludidos y aludidas no est\u00e1n, para nada, mancos. Cada uno tuvo su cierre en la medida de sus posibilidades -porque tampoco es que la renta de locales y de equipo; la log\u00edstica y la movilizaci\u00f3n salgan muy baratas-, pero a lo largo de este proceso fue muy evidente qui\u00e9nes tra\u00edan la cartera m\u00e1s abultada. O al menos, la de sus apoyadores \u2018cuello 18\u2019, que nunca faltan en este tipo de contiendas, algunos con apuestas en una y otro aspirante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorenia Valles cerr\u00f3 el s\u00e1bado, justo el d\u00eda de las personas mayores, acaso el sector m\u00e1s beneficiado y el voto m\u00e1s duro de Morena a partir de las pensiones que AMLO increment\u00f3 y entreg\u00f3 directamente a los beneficiarios, con un programa que Sheinbaum ha mantenido y ampliado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Javier Lamarque cerr\u00f3 en su tierra, Cajeme, en un encuentro con miles de mujeres del sur del estado, que le manifestaron su apoyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Los otros tres aspirantes: Mar\u00eda Dolores del R\u00edo, Omar del Valle Colosio y Froyl\u00e1n G\u00e1mez hicieron lo propio, aunque con eventos menos nutridos, lo que, han dicho, no los hace menos en sus expectativas de haber llegado a los mejores niveles de posicionamiento no solo entre la militancia, sino entre la poblaci\u00f3n abierta, porque finalmente ese es el universo que ser\u00e1 consultado para determinar qui\u00e9n abanderar\u00e1 a la coalici\u00f3n que encabeza Morena rumbo a la sucesi\u00f3n gubernamental 2027.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Esta etapa del proceso ha concluido y solo falta esperar el resultado, y ver si se hacen buenas las voluntades unitarias una vez conocido el nombre de el o la ganadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Pero no se desanime, festiva lectora, encampa\u00f1ado lector. En realidad esto apenas comienza, porque todav\u00eda falta la definici\u00f3n de coordinadores(as) en municipios, distritos locales y distritos federales, de manera que ya puede ir preparando el recalentado para recibir a la legi\u00f3n de aspirantes, al menos hasta diciembre\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;II<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La nota roja del fin de semana fue la incursi\u00f3n de un grupo armado a las instalaciones del Centro de Usos M\u00faltiples, donde se llevar\u00e1 a cabo una funci\u00f3n de box entre \u2018influencers\u2019 -algunos de reconocida fama en el tenebroso mundo del crimen, donde aparecen ligados a un grupo criminal- que finalmente fue cancelada porque los malosos quemaron hasta el ring.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento fue at\u00edpico. No hay antecedentes de algo parecido en Sonora y mueve a la reflexi\u00f3n sobre los alcances que tienen estas bandas criminales con capacidad (\u00bfo permiso?) para invadir un espacio p\u00fablico echando bala a discreci\u00f3n, apenas a una cuadra de la Comandancia Norte de la Polic\u00eda Municipal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Afortunadamente no hubo bajas qu\u00e9 lamentar, ni personas heridas en la refriega, La Fiscal\u00eda estatal inform\u00f3 que 24 personas ya han declarado sobre estos hechos, entre ellos testigos, influencers, promotores, boxeadores y personal t\u00e9cnico. Asegur\u00f3 que no se trat\u00f3 de un \u2018cobro de piso\u2019, sino de una agresi\u00f3n entre dos grupos delictivos dedicados al narcomenudeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Ah, bueno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;III<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La observadora lectora, el aguzado lector se habr\u00e1n fijado en los detalles de la imagen que documenta el acuerdo que puso fin a un plant\u00f3n de 129 d\u00edas frente al Congreso del Estado, y a una huelga de hambre de 99 d\u00edas (no se asombren: en el a\u00f1o 2000, la activista india Irom Sharmila comenz\u00f3 una huelga de hambre que dur\u00f3 16 a\u00f1os, aunque con la particularidad de que fue alimentada a la fuerza por las autoridades a trav\u00e9s de una sonda nasal durante m\u00e1s de 5 mil 500 d\u00edas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Pero ese no es el punto. Lo notable en la imagen que ilustr\u00f3 la firma del acuerdo entre las integrantes de Covafam (una asociaci\u00f3n civil que administra estancias infantiles y que reclamaba dos millones de pesos correspondientes al presupuesto 2023) y el gobernador Alfonso Durazo, es que no tuvo como sede el despacho del primer mandatario, sino el de su Jefa de Oficina, Paulina Oca\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El detalle no es menor: indica que buena parte de las negociaciones con las inconformes corrieron a cargo de la joven y experimentada funcionaria, que jug\u00f3 un papel importante en el tendido de puentes para alcanzar los acuerdos que terminaron con tres meses de conflicto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobernador firm\u00f3 el acuerdo; el secretario de Gobierno Adolfo Salazar aport\u00f3 la experiencia institucional, y Paulina Oca\u00f1a la operaci\u00f3n para permitir que por fin, las partes se encontraran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;IV<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto en la capital de Sonora, hubo dos buenas para el alcalde Antonio Astiazar\u00e1n, y otra que pudo ser m\u00e1s buena a\u00fan, pero le rasparon el mueble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La primera buena es el primer lugar obtenido por el Programa CRECES en la categor\u00eda Innovaci\u00f3n en Participaci\u00f3n Ciudadana de los premios NovaGob M\u00e9xico 2006 que se llev\u00f3 a cabo en Guadalajara, Jalisco. NovaGob es una organizaci\u00f3n sin fines de lucro dedicada a impulsar la innovaci\u00f3n p\u00fablica mediante la colaboraci\u00f3n entre administraciones, academia, sector privado y sociedad civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CRECES es un programa que lleva a consulta ciudadana las obras p\u00fablicas que deben hacerse en colonias, zonas y sectores de la ciudad, a partir de propuestas surgidas de los propios habitantes de la capital. Es, b\u00e1sicamente, un ejercicio de democratizaci\u00f3n de la toma de decisiones en cuanto al destino del presupuesto municipal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La segunda buena es otro reconocimiento nacional a la administraci\u00f3n de \u201cEl To\u00f1o\u201d, este de parte de la revista Alcaldes de M\u00e9xico, en la categor\u00eda de Gesti\u00f3n Financiera Responsable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Hermosillo recibi\u00f3 el premio en manos de la tesorera Flor Ayala Robles Linares \u201cpor la optimizaci\u00f3n del gasto p\u00fablico y por mantener finanzas sanas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La tercera, que pudo ser la mejor por su significado social, por el compromiso sobre un tema que nos lastima a todos, es la inauguraci\u00f3n de un monumento que visibiliza el trabajo de las Madres Buscadoras, esa legi\u00f3n de mujeres que van por la vida cargando el drama, la desaz\u00f3n y la incertidumbre por sus familiares desaparecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, el To\u00f1o Astiazar\u00e1n es el \u00fanico alcalde en el pa\u00eds, que ha concretado una iniciativa en este sentido. La estatua se encuentra ubicada en la esquina de Rosales y Pino Su\u00e1rez, en el coraz\u00f3n del Centro Hist\u00f3rico de Hermosillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Pero le rasparon el mueble, digo, porque en pleno discurso del alcalde, una madre buscadora le reclam\u00f3 los a\u00f1os que tiene ella buscando a su hijo, sin que el alcalde se haya acercado a ofrecerle siquiera una botella de agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Fue m\u00e1s all\u00e1: acus\u00f3 a la Polic\u00eda Municipal de estar involucrada en las desapariciones, lo que constituye una fuerte denuncia sobre un tema por dem\u00e1s escabroso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En el evento estuvieron presentes Cecy Flores, acaso la madre buscadora que ha ganado m\u00e1s visibilidad en M\u00e9xico sobre esa estampa tan dolorosa, y Cecilia Delgado, del Colectivo Buscadoras por la Paz, que agradecieron al alcalde ser el primero en rendir tributo a quienes dedican sus vidas a buscar a sus familiares desaparecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El tema es serio. La politizaci\u00f3n del caso tambi\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;Me puedes seguir en X: @Chaposoto<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Visita www.elzancudo.com.mx<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Columna El Zancudo Arturo Soto Mungu\u00eda Cierran fuerte en la 4T: pero falta la encuesta Lunes 31 de agosto de 2026 *Paulina Oca\u00f1a: clave para destrabar conflicto de Covafam A tambor batiente cerraron las asambleas informativas de los seis aspirantes de Morena a la CDTYSN (abreviatura muy \u00fatil para ahorrarnos el eufemismo con el que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[125],"tags":[],"class_list":["post-44594","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arturo-soto-munguia"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/44594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=44594"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/44594\/revisions"}],"predecessor-version":[{"id":44596,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/44594\/revisions\/44596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/44595"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=44594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=44594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=44594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}