{"id":30734,"date":"2025-07-12T23:27:26","date_gmt":"2025-07-13T06:27:26","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=30734"},"modified":"2025-07-12T23:27:31","modified_gmt":"2025-07-13T06:27:31","slug":"estados-unidos-amenaza-a-mexico-con-un-arancel-del-30-por-no-frenar-a-los-carteles-del-fentanilo","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/07\/12\/estados-unidos-amenaza-a-mexico-con-un-arancel-del-30-por-no-frenar-a-los-carteles-del-fentanilo\/","title":{"rendered":"Estados Unidos amenaza a M\u00e9xico con un arancel del 30% por no frenar a los carteles del fentanilo"},"content":{"rendered":"\n<p><strong>El presidente de EE UU ha anunciado en su red social que el gravamen, que M\u00e9xico considera \u201cinjusto\u201d, entrar\u00e1 en vigor el 1 de agosto<\/strong><\/p>\n\n\n\n<p>Tomado de El Pa\u00eds<\/p>\n\n\n\n<p>Mar\u00eda Antonia S\u00e1nchez<\/p>\n\n\n\n<p>S\u00e1bado 12 de julio de 2025<\/p>\n\n\n\n<p>Nueva York.- Estados Unidos impondr\u00e1 a partir del 1 de agosto un arancel del 30% a los productos y mercanc\u00edas importados desde M\u00e9xico, ha anunciado a primera hora de este s\u00e1bado el presidente estadounidense, Donald Trump, mediante una carta dirigida a su hom\u00f3loga mexicana, Claudia Sheinbaum, y publicada en su red social Truth. El mandatario republicano justifica su amenaza \u201cpara lidiar con la crisis del fentanilo de nuestro pa\u00eds, causada en parte por el fracaso de M\u00e9xico a la hora de frenar a los carteles (\u2026) a la hora de llenar de droga este pa\u00eds\u201d, escribe Trump.<\/p>\n\n\n\n<p>\u201cM\u00e9xico me ha estado ayudando a hacer segura la frontera, PERO (en may\u00fasculas en el original) lo que ha hecho no es suficiente. M\u00e9xico a\u00fan no ha detenido a los carteles que intentan hacer de toda Norteam\u00e9rica un terreno de juego del narcotr\u00e1fico. No puedo dejar que eso suceda. A partir del 1 de agosto, impondr\u00e9 a M\u00e9xico un arancel del 30% a todos los productos enviados a EE UU, al margen de los grav\u00e1menes sectoriales [cobre, aluminio, acero y autom\u00f3viles]. Las exportaciones [de M\u00e9xico] que intenten evadir esta carga ser\u00e1n sometidas a aranceles m\u00e1s altos\u201d.<\/p>\n\n\n\n<p>El anuncio del arancel a M\u00e9xico, de la misma cuant\u00eda que el impuesto a la Uni\u00f3n Europea, se conoce d\u00edas despu\u00e9s de que el republicano gravara con un 35% las importaciones de su otro socio preferente, Canad\u00e1, y un 50% todas las de Brasil, cinco veces el gravamen impuesto a Brasilia el 2 de abril \u2014aplazadas posteriormente 90 d\u00edas\u2014. El arancel a Brasil es una represalia al trato que sus autoridades est\u00e1n dando al expresidente Jair Bolsonaro, al que Trump considera v\u00edctima de una \u201ccaza de brujas\u201d en el juicio por su participaci\u00f3n en el golpe de enero de 2023, despu\u00e9s de haber perdido las elecciones meses antes.<\/p>\n\n\n\n<p>La canciller\u00eda y el ministerio de Econom\u00eda de M\u00e9xico han reaccionado a la carta de Trump recordando que los dos pa\u00edses hab\u00edan entablado negociaciones comerciales la v\u00edspera. \u201cResulta muy relevante haber establecido desde el 11 de julio la v\u00eda y el espacio necesarios para resolver cualquier posibilidad de que entren en vigor nuevos aranceles el 1\u00b0 de agosto. Es decir, M\u00e9xico ya est\u00e1 en negociaciones\u201d, reza el comunicado conjunto.<\/p>\n\n\n\n<p>En ese contacto, prosigue la nota oficial, \u201cse trataron temas de seguridad, migraci\u00f3n, frontera y gesti\u00f3n de aguas, as\u00ed como la relaci\u00f3n econ\u00f3mica entre ambos pa\u00edses. Nos fue dado a conocer que, como parte del cambio profundo en la pol\u00edtica comercial de EE UU, todos los pa\u00edses recibir\u00edan una carta signada por el presidente de los Estados Unidos, estableciendo nuevas tarifas a partir del 1\u00b0 de agosto. Mencionamos en la mesa que era un trato injusto y que no est\u00e1bamos de acuerdo\u201d.<\/p>\n\n\n\n<p>En abril pasado, cuando Trump lanz\u00f3 su bater\u00eda de los \u201caranceles rec\u00edprocos\u201d para 185 pa\u00edses, Trump hab\u00eda excluido sus socios del TMEC, Canad\u00e1 y M\u00e9xico. Esto supuso que los productos que cumplen con el tratado comercial siguieron libres de arancel, mientras que los que no cumpl\u00edan con el acuerdo pagaron una tarifa del 25%. El documento de la Casa Blanca a\u00f1ad\u00eda que una vez que se anulen las \u00f3rdenes de emergencia sobre fentanilo y migraci\u00f3n, los productos que cumplen con el acuerdo comercial seguir\u00edan recibiendo trato preferencial, mientras que los que no lo cumpl\u00edan estaban sujetos a un arancel rec\u00edproco de un 12%.<\/p>\n\n\n\n<p>La exclusi\u00f3n de M\u00e9xico de los aranceles rec\u00edprocos supuso en principio un alivio parcial a la carga impositiva que EE UU ha venido ejerciendo sobre las exportaciones mexicanas desde marzo pasado. La segunda econom\u00eda de Am\u00e9rica Latina tiene sobre sus hombros el cobro de un 25% sobre las exportaciones excluidas en el TMEC, que suponen hasta ahora el 50% de sus env\u00edos a Estados Unidos, as\u00ed como el arancel del 25% sobre el acero y aluminio.<\/p>\n\n\n\n<p>M\u00e9xico es el principal pa\u00eds del que importa EE UU. El pa\u00eds env\u00eda m\u00e1s del 80% de sus exportaciones a su vecino, por un valor de m\u00e1s de 500.000 millones de d\u00f3lares anuales.<\/p>\n\n\n\n<p>El mi\u00e9rcoles pasado, Sheinbaum, quien siempre evit\u00f3 la confrontaci\u00f3n directa con Trump, anunci\u00f3 el env\u00edo a Washington de una delegaci\u00f3n de altos funcionarios de M\u00e9xico el viernes para trabajar en el \u201cacuerdo general\u201d que le propuso a su hom\u00f3logo en el marco de la reuni\u00f3n de l\u00edderes del G-7, el mes pasado. La propuesta versa sobre migraci\u00f3n, seguridad en la frontera y, por supuesto, comercio. Sheinbaum dijo que su Gobierno har\u00eda todo lo posible por negociar las mejores condiciones para M\u00e9xico frente a las nuevas amenazas arancelarias. \u201cVamos a hacer todo el esfuerzo que est\u00e9 de nuestro lado. Sabe el pueblo de M\u00e9xico que estamos en eso\u201d, dijo el pasado mi\u00e9rcoles en una rueda de prensa.<\/p>\n\n\n\n<p>El plan inicial era que la delegaci\u00f3n de Sheinbaum aprovechase su visita a Washington para abordar la situaci\u00f3n de M\u00e9xico frente a los grav\u00e1menes que Trump busca imponer a las exportaciones de cobre (del 50%) y los productos farmac\u00e9uticos (de hasta 200%). \u201cNosotros siempre vamos a buscar las mejores condiciones para M\u00e9xico. Las decisiones muchas veces son del Gobierno de Estados Unidos, y nosotros buscamos poder generar, por ejemplo, en el caso del cobre, otros esquemas de exportaci\u00f3n, porque el cobre se requiere en muchos lugares del mundo. Entonces ah\u00ed hay algunas opciones\u201d, dijo Sheinbaum.<\/p>\n\n\n\n<p>https:\/\/elpais.com\/internacional\/2025-07-12\/estados-unidos-amenaza-a-mexico-con-un-arancel-del-30-por-no-frenar-a-los-carteles-del-fentanilo.html28 CST<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de EE UU ha anunciado en su red social que el gravamen, que M\u00e9xico considera \u201cinjusto\u201d, entrar\u00e1 en vigor el 1 de agosto Tomado de El Pa\u00eds Mar\u00eda Antonia S\u00e1nchez S\u00e1bado 12 de julio de 2025 Nueva York.- Estados Unidos impondr\u00e1 a partir del 1 de agosto un arancel del 30% a los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[7,3,115,105],"tags":[],"class_list":{"0":"post-30734","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"category-mexico","9":"category-politica","10":"category-principal"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/30734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=30734"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/30734\/revisions"}],"predecessor-version":[{"id":30736,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/30734\/revisions\/30736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/30735"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=30734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=30734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=30734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}