{"id":30602,"date":"2025-07-09T22:53:13","date_gmt":"2025-07-10T05:53:13","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=30602"},"modified":"2025-07-09T22:54:49","modified_gmt":"2025-07-10T05:54:49","slug":"estados-unidos-ordena-cierre-inmediato-al-ganado-mexicano-por-nuevo-caso-de-gusano-barrenador","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/07\/09\/estados-unidos-ordena-cierre-inmediato-al-ganado-mexicano-por-nuevo-caso-de-gusano-barrenador\/","title":{"rendered":"Estados Unidos ordena cierre inmediato al ganado mexicano por nuevo caso de gusano barrenador"},"content":{"rendered":"\n<p><strong>El cierre de la frontera se da tan solo un d\u00eda despu\u00e9s de que se hab\u00edan reactivado las exportaciones, ante una estrategia de ambas naciones para monitorear y combatir esta plaga.<\/strong><\/p>\n\n\n\n<p>Tomado de Aristegui Noticias<\/p>\n\n\n\n<p>Redacci\u00f3n AN\/ SBH<\/p>\n\n\n\n<p>Mi\u00e9rcoles 9 de julio de 2025<\/p>\n\n\n\n<p>Estados Unidos ordena cierre inmediato al ganado mexicano por nuevo caso de gusano barrenador<\/p>\n\n\n\n<p>El Departamento de Agricultura de Estados Unidos orden\u00f3 el cierre inmediato del comercio de ganado proveniente de M\u00e9xico. La titular del departamento, Brooke Rollins, argument\u00f3 que la decisi\u00f3n se debe a un nuevo caso de gusano barrenador en Ixhuatl\u00e1n de Madero, Veracruz.<\/p>\n\n\n\n<p>En comunicado, se inform\u00f3 que el caso fue confirmado por el Servicio Nacional de Sanidad, Inocuidad y Calidad Agroalimentaria (SENASICA) de M\u00e9xico.<\/p>\n\n\n\n<p>Seg\u00fan Estados Unidos, el nuevo reporte se encuentra aproximadamente a 257 kil\u00f3metros al norte de la red actual de dispersi\u00f3n de moscas est\u00e9riles, en el lado este del pa\u00eds y 595 kil\u00f3metros al sur de la frontera entre Estados Unidos y M\u00e9xico.<\/p>\n\n\n\n<p>Esta nueva detecci\u00f3n en direcci\u00f3n norte se produce aproximadamente dos meses despu\u00e9s de que se reportaran casos en el norte de Oaxaca y Veracruz, lo que provoc\u00f3 el cierre de los puertos al ganado, bisontes y caballos mexicanos el 11 de mayo de 2025.<\/p>\n\n\n\n<p>El cierre de la frontera se da tan solo un d\u00eda despu\u00e9s de que se hab\u00edan reactivado las exportaciones, ante una estrategia de ambas naciones para monitorear y combatir esta plaga.<\/p>\n\n\n\n<p>Para Estados Unidos, este nuevo caso genera gran preocupaci\u00f3n sobre la informaci\u00f3n previamente reportada por las autoridades mexicanas y compromete gravemente el cronograma de reapertura portuaria previsto para cinco puertos, del 7 de julio al 15 de septiembre.<\/p>\n\n\n\n<p>La secretaria Rollins ha ordenado el cierre del comercio de ganado a trav\u00e9s de los puertos de entrada del sur con efecto inmediato, para proteger al ganado estadounidense y el suministro de alimentos, dice el comunicado.<\/p>\n\n\n\n<p>\u201cNecesitamos ver m\u00e1s avances en la lucha contra el gusano barrenador en Veracruz y otros estados mexicanos cercanos para reabrir los puertos ganaderos a lo largo de la frontera sur\u201d, declar\u00f3 la secretaria de Agricultura.<\/p>\n\n\n\n<p>Para garantizar la protecci\u00f3n del ganado, Estados Unidos exige responsabilidades a M\u00e9xico, garantizando la adopci\u00f3n de medidas proactivas para mantener una barrera libre de esta plaga, apunta la comunicaci\u00f3n oficial<\/p>\n\n\n\n<p>El Consejo Nacional Agropecuario de M\u00e9xico expres\u00f3 \u2018preocupaci\u00f3n\u2019 por este nuevo cierre y se dijo dispuesto a laborar para solucionar la situaci\u00f3n:<\/p>\n\n\n\n<p><a href=\"https:\/\/aristeguinoticias.com\/090725\/mexico\/estados-unidos-ordena-cierre-inmediato-al-ganado-mexicano-por-nuevo-caso-de-gusano-barrenador\/\">https:\/\/aristeguinoticias.com\/090725\/mexico\/estados-unidos-ordena-cierre-inmediato-al-ganado-mexicano-por-nuevo-caso-de-gusano-barrenador\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cierre de la frontera se da tan solo un d\u00eda despu\u00e9s de que se hab\u00edan reactivado las exportaciones, ante una estrategia de ambas naciones para monitorear y combatir esta plaga. Tomado de Aristegui Noticias Redacci\u00f3n AN\/ SBH Mi\u00e9rcoles 9 de julio de 2025 Estados Unidos ordena cierre inmediato al ganado mexicano por nuevo caso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[114,7,3,2,105],"tags":[],"class_list":{"0":"post-30602","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"category-internacional","9":"category-mexico","10":"category-negocios","11":"category-principal"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/30602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=30602"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/30602\/revisions"}],"predecessor-version":[{"id":30604,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/30602\/revisions\/30604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/30603"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=30602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=30602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=30602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}