{"id":28747,"date":"2025-05-26T22:55:46","date_gmt":"2025-05-27T05:55:46","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=28747"},"modified":"2025-05-26T22:55:50","modified_gmt":"2025-05-27T05:55:50","slug":"asi-es-la-lujosa-propiedad-del-diputado-de-morena-arturo-avila-en-una-exclusiva-zona-de-california-eeuu","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/05\/26\/asi-es-la-lujosa-propiedad-del-diputado-de-morena-arturo-avila-en-una-exclusiva-zona-de-california-eeuu\/","title":{"rendered":"As\u00ed es la lujosa propiedad del diputado de Morena, Arturo \u00c1vila, en una exclusiva zona de California, EEUU"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La vivienda ha sido valuada en un m\u00e1ximo de USD 4.8 millones y se encuentra en una de las zonas m\u00e1s caras de Estados Unidos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tomado de Infobae<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel Aguilar Esquivel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lunes 26 de mayo de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" height=\"1080\" width=\"1920\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/PGQYKDKTQREYFGUSGXECH5XLTM.jpg?auth=25ebdc463fc444111050904b4ab0cc6894f82b31e1a9a117c2e216fe8c28babf&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" alt=\"El legislador de Morena confirm\u00f3\">El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas de Estados Unidos (Homes.com)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arturo \u00c1vila Anaya<\/strong>, diputado federal y vocero del grupo parlamentario del Movimiento de Regeneraci\u00f3n Nacional (<strong>Morena<\/strong>), adquiri\u00f3 una propiedad en los Estados Unidos cuyo valor estimado es de&nbsp;<strong>USD 4.8 millones<\/strong>. La casa en cuesti\u00f3n se encuentra ubicada en&nbsp;<strong>Rancho Santa Fe<\/strong>, California, es decir en la zona residencial m\u00e1s cara del estado y una de las m\u00e1s costosas de los Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.infobae.com\/mexico\/2025\/05\/26\/luisa-maria-alcalde-responde-mauricio-kuri-gobernador-de-queretaro-que-pidio-no-votar-por-morena\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" height=\"658\" width=\"878\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/BCBXJ2J4SFA2VNRTKMVBKDIQWM.jpg?auth=2176192cba3b6be7023b0fe958027d91fb28d537ed8c63afb11ebe8ebd549f87&amp;smart=true&amp;width=350&amp;height=263&amp;quality=85\" alt=\"El legislador de Morena confirm\u00f3\">El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas de Estados Unidos (Homes.com)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con una investigaci\u00f3n de Mexicanos Contra la Corrupci\u00f3n y la Impunidad (MCCI), el legislador adquiri\u00f3 la propiedad en marzo del 2024, a trav\u00e9s de una hipoteca con valor de&nbsp;<strong>USD 1.9 millones<\/strong>, es decir MXN 93 millones 573 mil 763, aproximadamente. Ello, a la par del bloqueo de cuentas bancarias que enfrent\u00f3 IBN Industrias Militares de Alta Tecnolog\u00eda Bal\u00edstica SA de CV, propiedad del legislador y su esposa.<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" alt=\"El legislador de Morena confirm\u00f3\" height=\"656\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/3YQN27CLBRFITMTENCVVVCVIX4.jpg?auth=95018b8a890a239492a14dc5a60ff15a5885e3904686241ed857c5cf071e6f24&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"984\">El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas de Estados Unidos (Homes.com)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la publicaci\u00f3n de la investigaci\u00f3n,&nbsp;<strong>Arturo \u00c1vila&nbsp;<\/strong>confirm\u00f3 la pertenencia de dicha propiedad a trav\u00e9s de su cuenta verificada de la red social X, antes Twitter. De igual manera, asegur\u00f3 que la compra se realiz\u00f3 dentro del marco legal y neg\u00f3 habitarla al aclarar que los inmuebles que ha adquirido los remodela para luego volverlos a vender.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.infobae.com\/mexico\/2025\/05\/27\/gobierno-de-baja-california-desmiente-que-marina-del-pilar-sea-duena-de-mansion-de-45-mdd-en-eeuu\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" height=\"658\" width=\"878\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/YCCENXLWYVBZPAUWGBLRR74D5U.jpg?auth=3f75be99f953e6ecf1266ba559627133c4350b75a1ab8c5b356152e8e2bfe0f5&amp;smart=true&amp;width=350&amp;height=263&amp;quality=85\" alt=\"El legislador de Morena confirm\u00f3\">El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas de Estados Unidos (Homes.com)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">As\u00ed es la lujosa propiedad del diputado de Morena, Arturo \u00c1vila, en una exclusiva zona de California, EEUU<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la investigaci\u00f3n, el inmueble se encuentra en el 17423 de la calle Circa del Sur, en San Diego, California, una zona a la que se debe acceder a trav\u00e9s de un m\u00f3dulo de seguridad fortificado con grandes rejas y estructuras.<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" alt=\"El legislador de Morena confirm\u00f3\" height=\"656\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/3BQ25FODZFG4TEXXC7KGVJSWIQ.jpg?auth=b9c6689cd2290b938ff0d381a4b416601fe842c53e195af2db4bafd9666545f8&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"984\">El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas de Estados Unidos (Homes.com)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la informaci\u00f3n publicada en el sitio web Homes.com, la propiedad cuenta con una superficie construida de&nbsp;<strong>5 mil 854 pies cuadrados<\/strong>. En su interior hay seis habitaciones, as\u00ed como cinco ba\u00f1os y medio. La rec\u00e1mara principal cuenta con chimenea, al igual que la sala de estar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.infobae.com\/mexico\/2025\/05\/26\/elimina-varices-aranitas-y-venas-varicosas-en-piernas-aplicando-este-aceite-esencial-que-pocos-conocen\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" height=\"656\" width=\"984\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/EDUVROP5ERFK3AM7DN5LLPVWLE.jpg?auth=f66294fdb90ebec289e28b2da42621c7689f3f278655608361747d6d7d0a30a1&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" alt=\"El legislador de Morena confirm\u00f3\">El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas de Estados Unidos (Homes.com)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Una finca tradicional ubicada en la exclusiva comunidad privada de&nbsp;<strong>Fairbanks Ranch<\/strong>. Disfrute de un dise\u00f1o abierto y vers\u00e1til con 5 de las 6 habitaciones en la planta principal\u201c, se lee en la descripci\u00f3n del sitio web.<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" alt=\"El legislador de Morena confirm\u00f3\" height=\"656\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/XQATCARKQNGHDARCAERW5WNIIY.jpg?auth=b0be36cd8a4f7bdfc7be7d94fde7a119c65a868556b9bdf4f9e4f650e106cf39&amp;smart=true&amp;width=350&amp;height=233&amp;quality=85\" width=\"984\">El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas de Estados Unidos (Homes.com)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vivienda unifamiliar construida en el a\u00f1o 1989 tambi\u00e9n cuenta con garaje adjunto para tres coches, aire acondicionado central, lavander\u00eda, patio trasero, una bodega con capacidad de almacenar mil 700 botellas, sala multimedia, sauna y un amplio espacio flexible.<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" alt=\"Ricardo Monreal destap\u00f3 a Arturo\" height=\"1080\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/OFRK7CKK4JG43L7V5CBT7VYONA.jpg?auth=2945d91fb5f594f427d88d7bdfee3314647cf6567b8562e587fa9c2deb2ed1fc&amp;smart=true&amp;width=350&amp;height=197&amp;quality=85\" width=\"1920\">Ricardo Monreal destap\u00f3 a Arturo \u00c1vila como aspirante a la gubernatura de Aguascalientes (X\/@Sergeluna_S)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comunidad cuenta con guardia de seguridad y el pago estimado de impuestos cada a\u00f1o es de\u00a0<strong>USD 28 mil 873<\/strong>, es decir MXN 555 mil 802, aproximadamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.infobae.com\/mexico\/2025\/05\/26\/asi-es-la-lujosa-propiedad-del-diputado-de-morena-arturo-avila-en-una-exclusiva-zona-de-california-eeuu\">https:\/\/www.infobae.com\/mexico\/2025\/05\/26\/asi-es-la-lujosa-propiedad-del-diputado-de-morena-arturo-avila-en-una-exclusiva-zona-de-california-eeuu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vivienda ha sido valuada en un m\u00e1ximo de USD 4.8 millones y se encuentra en una de las zonas m\u00e1s caras de Estados Unidos Tomado de Infobae Israel Aguilar Esquivel Lunes 26 de mayo de 2025 El legislador de Morena confirm\u00f3 haber adquirido una propiedad dentro de una de las zonas residenciales m\u00e1s costosas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,115],"tags":[],"class_list":["post-28747","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mexico","category-politica"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/28747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=28747"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/28747\/revisions"}],"predecessor-version":[{"id":28749,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/28747\/revisions\/28749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/28748"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=28747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=28747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=28747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}