{"id":27078,"date":"2025-04-14T14:14:14","date_gmt":"2025-04-14T21:14:14","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=27078"},"modified":"2025-04-14T14:15:18","modified_gmt":"2025-04-14T21:15:18","slug":"por-nacionalizacion-de-exportadora-de-sal-en-mexico-empresa-japonesa-se-lleva-clientes","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/04\/14\/por-nacionalizacion-de-exportadora-de-sal-en-mexico-empresa-japonesa-se-lleva-clientes\/","title":{"rendered":"Por nacionalizaci\u00f3n de exportadora de sal en M\u00e9xico, empresa japonesa se lleva clientes"},"content":{"rendered":"\n<p>Tomado de Milenio<\/p>\n\n\n\n<p>Fabby Mirabda<\/p>\n\n\n\n<p>Lunes 14 de abril de 2025<a href=\"https:\/\/dossierpolitico.com\/wp-content\/uploads\/2025\/04\/1gm9fm15.png\"><\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/dossierpolitico.com\/2025\/04\/14\/por-nacionalizacion-de-exportadora-de-sal-en-mexico-empresa-japonesa-se-lleva-clientes\/#\"><\/a><\/p>\n\n\n\n<p><em>Bajo la administraci\u00f3n de Sheinbaum, la nueva direcci\u00f3n logr\u00f3 en los primeros 100 d\u00edas de gobierno, colocar el qu\u00edmico en el mercado internacional para normalizar la producci\u00f3n.<\/em><a href=\"https:\/\/dossierpolitico.com\/2025\/04\/14\/por-nacionalizacion-de-exportadora-de-sal-en-mexico-empresa-japonesa-se-lleva-clientes\/#\"><\/a>\u00a0<a href=\"https:\/\/dossierpolitico.com\/2025\/04\/14\/por-nacionalizacion-de-exportadora-de-sal-en-mexico-empresa-japonesa-se-lleva-clientes\/#\"><\/a><\/p>\n\n\n\n<p>Tras la nacionalizaci\u00f3n de la&nbsp;<strong>Exportadora de Sal<\/strong>, durante el gobierno de Andr\u00e9s Manuel L\u00f3pez Obrador en febrero de 2024, la&nbsp;<strong>empresa japonesa Mitsubishi&nbsp;<\/strong>se llev\u00f3 la cartera de clientes, por lo que una monta\u00f1a de 3 millones de toneladas de sal se acumul\u00f3 a lo largo de un a\u00f1o.&nbsp;<\/p>\n\n\n\n<p>Bajo la administraci\u00f3n de la presidenta&nbsp;<a href=\"https:\/\/www.milenio.com\/estados\/presidenta-claudia-sheinbaum-visita-tamaulipas-11-abril\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Claudia Sheinbaum,<\/strong><\/a><strong><\/strong>&nbsp;la nueva direcci\u00f3n logr\u00f3 en los primeros 100 d\u00edas de gobierno, colocar el qu\u00edmico en el&nbsp;<strong>mercado internacional<\/strong>&nbsp;para normalizar la producci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.milenio.com\/uploads\/media\/2025\/04\/13\/el-mayor-volumen-de-produccion.jpg\" alt=\"Descripci\u00f3n de la imagen\"\/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEl a\u00f1o 2024 fue muy complicado, porque se dio la<strong>&nbsp;venta de las acciones de Mitsubishi<\/strong>, se dio la nacionalizaci\u00f3n, se volvi\u00f3 una empresa completamente paraestatal, pero no se ten\u00eda bien focalizado el \u00e1rea de comercializaci\u00f3n.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEntonces, en los primeros cien d\u00edas, la tarea m\u00e1s apremiante que me dio el secretario (de Econom\u00eda) Marcelo Ebrad, fue colocar el producto, darle certeza de ventas a esta compa\u00f1\u00eda\u201d, se\u00f1al\u00f3 Mois\u00e9s Poblanno Silva, director general de Exportadora de Sal S.A. de C.V.<\/p>\n<\/blockquote>\n\n\n\n<p>La&nbsp;<strong>Exportadora de Sal, S.A. de C.V<\/strong>. (ESSA) es una concesi\u00f3n minera que se encuentra dentro de la Reserva de la Biosfera El Vizca\u00edno, que con m\u00e1s de 33 mil hect\u00e1reas -rentadas a cinco ejidos\u2013, constituye la salinera m\u00e1s grande del mundo.<\/p>\n\n\n\n<p>En un recorrido realizado por&nbsp;<strong>MILENIO<\/strong>, Poblanno Silva mostr\u00f3 cada uno de los&nbsp;<strong>procesos de obtenci\u00f3n de la sal marina<\/strong>, cuyo uso es industrial; as\u00ed llegamos a la monta\u00f1a que ahora, se estima en 1.2 millones de&nbsp;<strong>sal acumulada<\/strong>, tras reactivar las exportaciones de la materia prima hacia pa\u00edses como&nbsp;<strong>China, Taiw\u00e1n, Jap\u00f3n, Corea, Estados Unidos, Costa Rica<\/strong>&nbsp;y pr\u00f3ximamente Qatar, entre otros.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.milenio.com\/uploads\/media\/2025\/04\/11\/salina-mas-grande-del-mundo.jpg\" alt=\"Descripci\u00f3n de la imagen\"\/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cLogramos en estos 100 d\u00edas poder colocar la sal ya en diferentes pa\u00edses, en diferentes&nbsp;<strong>mercados internacionales<\/strong>; es un paso adelante para la empresa porque era algo que sin el socio japon\u00e9s era muy complicado.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cLos funcionarios del&nbsp;<strong>gobierno de M\u00e9xico<\/strong>&nbsp;nunca tuvieron la tarea de comercializar el producto, no porque no quisieran, sino porque no era parte de sus funciones. Esa fue una de las tareas que el socio japon\u00e9s llev\u00f3 a cabo a lo largo de las d\u00e9cadas en que fue socio de la empresa\u201d, precis\u00f3 Mois\u00e9s Poblanno.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>As\u00ed fue la nacionalizaci\u00f3n de la Exportadora de Sal<\/strong><\/h2>\n\n\n\n<p>Fue el 24 de febrero de 2024, cuando el<strong>&nbsp;gobierno de Andr\u00e9s Manuel L\u00f3pez Obrador&nbsp;<\/strong>nacionaliz\u00f3 la empresa Exportadora de Sal; la compa\u00f1\u00eda ten\u00eda una participaci\u00f3n estatal mayoritaria del 51 por ciento y el resto pertenec\u00eda a la&nbsp;<strong>empresa japonesa Mitsubishi,<\/strong>&nbsp;por lo que el&nbsp;<a href=\"https:\/\/www.milenio.com\/negocios\/restriccion-horarios-autotransporte-carga-semana-santa\">gobierno<\/a>&nbsp;invirti\u00f3 mil 500 millones de pesos a fin de adquirir la totalidad de las&nbsp;<strong>acciones.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cLa&nbsp;<strong>inversi\u00f3n&nbsp;<\/strong>para comprar las acciones de esta empresa son del fondo minero. Que antes se robaban el fondo minero, me consta, se lo entregaban a gobiernos municipales, gobiernos estatales, y desaparec\u00eda el fondo minero\u201d, dijo el entonces presidente, durante la firma del convenio por la nacionalizaci\u00f3n de la empresa, realizada en el municipio de Muleg\u00e9.<\/p>\n<\/blockquote>\n\n\n\n<p>En aquel momento, la secretaria de Econom\u00eda, Raquel Buenrostro, precis\u00f3 que no se trat\u00f3 de una expropiaci\u00f3n sino de un acuerdo alcanzado con directivos de Mitsubishi. Resalt\u00f3 que hasta esa fecha \u20132024\u2013, la<strong>&nbsp;Exportadora de Sal<\/strong>&nbsp;reportaba una producci\u00f3n superior a los 8 millones de toneladas anuales, con capacidad de abastecer a la industria de la regi\u00f3n Asia-Pac\u00edfico y Costa Este de Am\u00e9rica del Norte; y con capacidad para recibir y cargar barcos de hasta 180 mil toneladas.<\/p>\n\n\n\n<p><strong>Los retos tras nacionalizar la Exportadora de Sal<\/strong><\/p>\n\n\n\n<p>Sin embargo, tras la salida de Mitsubishi que se llev\u00f3 la cartera de clientes, la producci\u00f3n cay\u00f3 de 8 millones de toneladas anuales, a menos de 5 millones para 2024. El actual director de la paraestatal asegur\u00f3 que este 2025, se alcanzar\u00e1 una&nbsp;<strong>producci\u00f3n<\/strong>&nbsp;de 7 millones de toneladas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEl 2024 fue un a\u00f1o complicado para la&nbsp;<strong>exportadora<\/strong>, porque no se pudo producir m\u00e1s porque no hab\u00eda donde almacenar m\u00e1s sal; por lo tanto, la producci\u00f3n baj\u00f3, tambi\u00e9n las ventas no fueron las que esperaban y hab\u00eda que almacenarla en alg\u00fan lado; por eso el apilamiento tanto en el puerto de&nbsp;<strong>Chaparrito como en Isla de Cedros<\/strong>&nbsp;ten\u00edan cerca de los 3 millones de toneladas almacenadas, cosa que hoy en d\u00eda el cerro del apilamiento ha ido disminuyendo a 1.2 millones de toneladas\u201d, se\u00f1al\u00f3 Mois\u00e9s Poblanno.<\/p>\n<\/blockquote>\n\n\n\n<p>El director de ESSA dijo que logr\u00f3 colocar la materia prima en el&nbsp;<strong>mercado internacional&nbsp;<\/strong>para este 2025, en un aproximado de 25 d\u00f3lares por tonelada; pero uno de los objetivos de la actual administraci\u00f3n es incorporar valor agregado, para obtener mayores ingresos y brindar mayor solvencia a la empresa.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cLa sal es un commodity y valdr\u00eda la pena incorporar valor agregado, generar algunos otros qu\u00edmicos que provienen de los productos de sodio o incorporarnos al nuevo mercado de las bater\u00edas de sodio que son m\u00e1s estables qu\u00edmicamente que las de litio. Veremos de qu\u00e9 manera poder incursionar en esos nuevos mercados\u201d.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.milenio.com\/uploads\/media\/2025\/04\/13\/este-se-alcanzara-una-produccion.jpg\" alt=\"Descripci\u00f3n de la imagen\"\/><\/figure>\n\n\n\n<p>Poblanno Silva destac\u00f3 que la paraestatal opera en n\u00fameros negros, y que fuera del costo del 49 por ciento de las acciones a&nbsp;<strong>Mitsubishi<\/strong>, el gobierno federal nunca ha transferido recursos a la empresa, lo que implica que se dej\u00f3 de invertir en infraestructura; por lo que al a\u00f1o se gasta cerca de 600 millones de pesos en&nbsp;<a href=\"https:\/\/www.milenio.com\/negocios\/gasolina-magna-y-diesel-se-quedan-sin-estimulo-fiscal-en-semana-santa\">di\u00e9sel<\/a>.<\/p>\n\n\n\n<p>Estim\u00f3 que se requiere una&nbsp;<strong>inversi\u00f3n&nbsp;<\/strong>de alrededor 5 millones de d\u00f3lares para modernizar la planta de lavado que data de hace 30 a\u00f1os, as\u00ed como el&nbsp;<strong>Puerto de Chaparrito<\/strong>&nbsp;donde se cargan las barcazas y el Puerto de Cedros, que es donde se cargan los barcos de alto calado.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cTodo ha sido productor del tiempo y la&nbsp;<strong>falta de inversi\u00f3n;<\/strong>&nbsp;sin embargo, con la visi\u00f3n que tuvo el presidente L\u00f3pez Obrador de nacionalizarla, hoy nos estamos reposicionando en el mundo.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cYa colocamos toda la&nbsp;<strong>producci\u00f3n del 2025,<\/strong>&nbsp;ya est\u00e1 comprometida la venta; ya empezamos el compromiso tambi\u00e9n con 2026 y 2027, que con esto se da certeza para la compa\u00f1\u00eda, certeza para los trabajadores, certeza para la comunidad de Guerrero Negro, de Baja California Sur y de M\u00e9xico\u201d, se\u00f1al\u00f3 Mois\u00e9s Poblanno Silva, director general de Exportadora de Sal S.A. de C.V.<\/p>\n<\/blockquote>\n\n\n\n<p>La ESSA aporta el 84 por ciento de la&nbsp;<strong>producci\u00f3n de sal<\/strong>&nbsp;en el pa\u00eds, orientada principalmente a la exportaci\u00f3n. M\u00e9xico est\u00e1 en el s\u00e9ptimo lugar a nivel mundial con la elaboraci\u00f3n de sal de 8.7 toneladas m\u00e9tricas y, junto con Chile, es uno de los principales productores de&nbsp;<a href=\"https:\/\/www.milenio.com\/politica\/eleccion-judicial-atractiva-grupos-margen-ley-observador\">Am\u00e9rica Latina.<\/a><\/p>\n\n\n\n<p>La&nbsp;<strong>exportadora&nbsp;<\/strong>cuenta con m\u00e1s de 70 a\u00f1os de operaci\u00f3n, y da empleo a mil 300 personas. Se f\u00e1brica sal marina con calidad superior al 99.7 por ciento de contenido de cloruro de sodio, debido a que en&nbsp;<strong>Guerrero Negro&nbsp;<\/strong>se cuentan con las&nbsp;<strong>condiciones biol\u00f3gicas<\/strong>&nbsp;y clim\u00e1ticas que hacen posible esa calidad.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.milenio.com\/uploads\/media\/2025\/04\/13\/la-essa-aporta-el-por.jpg\" alt=\"Descripci\u00f3n de la imagen\"\/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cHay viento, hay sol, hay poca lluvia al a\u00f1o y estos son los elementos que permiten que se pueda cristalizar en los vasos de producci\u00f3n y despu\u00e9s que se pueda cosechar para su correspondiente lavado y despu\u00e9s su distribuci\u00f3n\u201d.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.milenio.com\/uploads\/media\/2025\/04\/13\/la-exportadora-cuenta-con-mas.jpg\" alt=\"Descripci\u00f3n de la imagen\"\/><\/figure>\n\n\n\n<p>De las 7 millones de toneladas de&nbsp;<strong>sal industrial&nbsp;<\/strong>que se producir\u00e1n, cerca de 100 mil toneladas corresponden a sal de mesa.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.milenio.com\/uploads\/media\/2025\/04\/13\/millones-toneladas-mil-corresponden-sal.jpg\" alt=\"Descripci\u00f3n de la imagen\"\/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEl mayor volumen de producci\u00f3n est\u00e1 en la sal industrial, aquella por su granolog\u00eda que son mayores tipos de grano que tienen tambi\u00e9n un nivel de pureza de entre el 99.7 y el 99.9 por ciento de pureza\u201d, destac\u00f3<strong>&nbsp;Mois\u00e9s Poblanno.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>\u200bLa sal que se produce en<strong>&nbsp;Guerrero Negro<\/strong>&nbsp;tiene aplicaciones en el sector qu\u00edmico, la&nbsp;<a href=\"https:\/\/www.milenio.com\/negocios\/trump-paro-dialogo-industria-farmaceutica-norteamerica-canifarma\" target=\"_blank\" rel=\"noreferrer noopener\">industria farmace\u00fatica<\/a>, en el tratamiento de agua potable o en la fabricaci\u00f3n de pl\u00e1sticos; mientras que las salmueras residuales se usan para el deshielo de carreteras, y para la obtenci\u00f3n de sal de mesa.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.milenio.com\/internacional\/empresa-japonesa-clientes-nacionalizacion-exportadora-mexico\">https:\/\/www.milenio.com\/internacional\/empresa-japonesa-clientes-nacionalizacion-exportadora-mexico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tomado de Milenio Fabby Mirabda Lunes 14 de abril de 2025 Bajo la administraci\u00f3n de Sheinbaum, la nueva direcci\u00f3n logr\u00f3 en los primeros 100 d\u00edas de gobierno, colocar el qu\u00edmico en el mercado internacional para normalizar la producci\u00f3n.\u00a0 Tras la nacionalizaci\u00f3n de la&nbsp;Exportadora de Sal, durante el gobierno de Andr\u00e9s Manuel L\u00f3pez Obrador en febrero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[114,3,2,105],"tags":[],"class_list":{"0":"post-27078","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"category-mexico","9":"category-negocios","10":"category-principal"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/27078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=27078"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/27078\/revisions"}],"predecessor-version":[{"id":27080,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/27078\/revisions\/27080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/27079"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=27078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=27078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=27078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}