{"id":27043,"date":"2025-04-12T21:46:27","date_gmt":"2025-04-13T04:46:27","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=27043"},"modified":"2025-04-12T21:46:30","modified_gmt":"2025-04-13T04:46:30","slug":"trump-perdona-smartphones-y-monitores-en-aranceles-reciprocos","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/04\/12\/trump-perdona-smartphones-y-monitores-en-aranceles-reciprocos\/","title":{"rendered":"Trump perdona &#8216;smartphones&#8217; y monitores en &#8216;aranceles rec\u00edprocos&#8217;"},"content":{"rendered":"\n<p>Aproximadamente el 90% de la producci\u00f3n y ensamblaje del iPhone de Apple se realiza en China, seg\u00fan estimaciones de Wedbush Securities.<\/p>\n\n\n\n<p>Tomado de Aristegui Notcias<\/p>\n\n\n\n<p>Redacci\u00f3n AN \/ JSC<\/p>\n\n\n\n<p>S\u00e1bado 12 de abril de 2025<\/p>\n\n\n\n<p>Los \u2018smartphones\u2018 y los monitores de ordenador son algunos de los dispositivos electr\u00f3nicos que EE.UU. ha decidido dejar libres de sus llamados \u201caranceles rec\u00edprocos\u201d, seg\u00fan un aviso oficial del Gobierno del presidente Donald Trump.<\/p>\n\n\n\n<p>La nueva directriz de la Oficina de Aduanas y Protecci\u00f3n Fronteriza de los Estados Unidos (CBP, en ingl\u00e9s), encargada de recaudar los aranceles sobre las importaciones, tambi\u00e9n incluye un listado con una veintena de componentes y dispositivos electr\u00f3nicos excluidos.<\/p>\n\n\n\n<p>Entre ellos se encuentran chips semiconductores, pantallas planas de televisi\u00f3n, unidades flash (\u2018pendrive\u2019) y tarjetas de memoria.<\/p>\n\n\n\n<p>Esta exenci\u00f3n, de acuerdo con el documento de CBP publicado en las \u00faltimas horas, se aplicar\u00e1 a aquellos productos importados a EE.UU. y que hayan ingresado al pa\u00eds norteamericano o salieran de los almacenes en sus lugares de origen a partir del 5 de abril.<\/p>\n\n\n\n<p>Esto podr\u00eda representar un alivio para los consumidores, quienes se enfrentaban a la posibilidad de pagar precios m\u00e1s altos principalmente por la guerra comercial entre Estados Unidos y China, y para gigantes tecnol\u00f3gicos norteamericanos como Apple, que fabrican gran parte de sus productos en el pa\u00eds asi\u00e1tico.<\/p>\n\n\n\n<p>De hecho, aproximadamente el 90% de la producci\u00f3n y ensamblaje del iPhone de Apple se realiza en China, seg\u00fan estimaciones de Wedbush Securities.<\/p>\n\n\n\n<p>Adem\u00e1s, seg\u00fan la firma de inversi\u00f3n Everscore IS, en China se fabrica el 80 % de los iPads y m\u00e1s de la mitad de los ordenadores Mac producidos.<\/p>\n\n\n\n<p>Desde el anuncio de la agresiva pol\u00edtica arancelaria de la Administraci\u00f3n Trump el pasado 2 de abril, Apple ha perdido m\u00e1s de 640 mil millones de d\u00f3lares en valor de mercado y Microsoft la ha superado como la cotizada m\u00e1s valiosa del mundo.<\/p>\n\n\n\n<p>Esta nueva directriz \u201celimina por ahora una enorme nube negra sobre el sector tecnol\u00f3gico y la presi\u00f3n a la que se enfrentan las grandes tecnol\u00f3gicas estadounidenses (\u2026) \u00c9stas no tienen otra opci\u00f3n, ya que la cadena de suministro se encuentra esencialmente en Asia\u201d, consider\u00f3 el responsable de investigaci\u00f3n tecnol\u00f3gica de Wedbush Securities, Dan Ives, en un comunicado.<\/p>\n\n\n\n<p>Esta semana, el presidente estadounidense, Donald Trump, pospuso la aplicaci\u00f3n de los \u201caranceles rec\u00edprocos\u201d 90 d\u00edas para negociar con los pa\u00edses que no hab\u00edan tomado represalias, pero mantuvo el impuesto base del 10% a todas las importaciones.<\/p>\n\n\n\n<p>Este giro de tim\u00f3n, sin embargo, no se aplic\u00f3 a China, a la que Trump ha incrementado los \u201caranceles rec\u00edprocos\u201d al 125%, m\u00e1s otro gravamen del 20% que ya pesaba en su contra (145% en total), provocando una respuesta proporcional de Pek\u00edn y el temor a una guerra comercial a gran escala.<\/p>\n\n\n\n<p>EFE<\/p>\n\n\n\n<p><a href=\"https:\/\/aristeguinoticias.com\/120425\/dinero-y-economia\/trump-perdona-smartphones-y-monitores-en-aranceles-reciprocos\">https:\/\/aristeguinoticias.com\/120425\/dinero-y-economia\/trump-perdona-smartphones-y-monitores-en-aranceles-reciprocos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aproximadamente el 90% de la producci\u00f3n y ensamblaje del iPhone de Apple se realiza en China, seg\u00fan estimaciones de Wedbush Securities. Tomado de Aristegui Notcias Redacci\u00f3n AN \/ JSC S\u00e1bado 12 de abril de 2025 Los \u2018smartphones\u2018 y los monitores de ordenador son algunos de los dispositivos electr\u00f3nicos que EE.UU. ha decidido dejar libres de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27044,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[114,7,105],"tags":[],"class_list":{"0":"post-27043","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"category-internacional","9":"category-principal"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/27043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=27043"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/27043\/revisions"}],"predecessor-version":[{"id":27045,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/27043\/revisions\/27045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/27044"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=27043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=27043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=27043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}