{"id":26952,"date":"2025-04-09T21:14:38","date_gmt":"2025-04-10T04:14:38","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=26952"},"modified":"2025-04-09T21:14:41","modified_gmt":"2025-04-10T04:14:41","slug":"sheinbaum-presente-en-la-ix-cumbre-de-celac-en-honduras","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/04\/09\/sheinbaum-presente-en-la-ix-cumbre-de-celac-en-honduras\/","title":{"rendered":"Sheinbaum, presente en la IX Cumbre de CELAC en Honduras"},"content":{"rendered":"\n<p><strong>La mandataria convers\u00f3 con su hom\u00f3logo, adem\u00e1s estuvo acompa\u00f1ada de L\u00e1zaro C\u00e1rdenas, jefe de la Oficina de la Presidencia; Raquel Serur, subsecretaria para Am\u00e9rica Latina y el Caribe.<\/strong><\/p>\n\n\n\n<p>Tomado de El Economista<\/p>\n\n\n\n<p>Redacci\u00f3n<\/p>\n\n\n\n<p>Mi\u00e9rcoles 9 de abril de 2025<\/p>\n\n\n\n<p>El d\u00eda de hoy la presidenta Claudia Sheinbaum viaj\u00f3 a Honduras para ser parte de la IX Cumbre de la Comunidad de Estados Latinoamericanos y Caribe\u00f1os (Celac). Estuvo acompa\u00f1ada por el secretario de Relaciones Exteriores (SRE), Juan Ram\u00f3n de la Fuente quien junto al presidente de Honduras, H\u00e9ctor Zelaya, la recibieron en el aeropuerto.<\/p>\n\n\n\n<p>La mandataria convers\u00f3 con su hom\u00f3logo hondure\u00f1o, adem\u00e1s estuvo acompa\u00f1ada de L\u00e1zaro C\u00e1rdenas, jefe de la Oficina de la Presidencia; Raquel Serur, subsecretaria para Am\u00e9rica Latina y el Caribe.<\/p>\n\n\n\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, reiter\u00f3 su participaci\u00f3n en la Cumbre de la CELAC y destac\u00f3 la importancia de este foro para fortalecer la integraci\u00f3n regional y reconoci\u00f3 la invitaci\u00f3n personal de su hom\u00f3loga hondure\u00f1a, Xiomara Castro.<\/p>\n\n\n\n<p><strong>Sheinbaum impulsar\u00e1 unidad de Am\u00e9rica Latina y el Caribe en la cumbre CELAC<\/strong><\/p>\n\n\n\n<p>Sheinbaum estar\u00e1 presente en la inauguraci\u00f3n de la Cumbre y tendr\u00e1 una participaci\u00f3n en la primera sesi\u00f3n plenaria. En la cumbre tambi\u00e9n asistir\u00e1n los presidentes Luiz In\u00e1cio Lula da Silva, de Brasil; Gustavo Petro, de Colombia; Bernardo Ar\u00e9valo, de Guatemala; Yamand\u00fa Orsi, de Uruguay; Miguel D\u00edaz-Canel, de Cuba, y la anfitriona Xiomara Castro, entre otros.<\/p>\n\n\n\n<p>Se llevar\u00e1 a cabo la Cumbre de L\u00edderes Regionales, donde Castro ceder\u00e1 la presidencia de la Celac a Petro, quien asumir\u00e1 la presidencia del foro. La Celac agrupa a 33 pa\u00edses de Am\u00e9rica Latina y el Caribe, tiene como prop\u00f3sito promover la integraci\u00f3n regional en aspectos econ\u00f3micos, sociales y culturales.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.eleconomista.com.mx\/politica\/sheinbaum-presente-ix-cumbre-celac-honduras-20250409-754220.html\">https:\/\/www.eleconomista.com.mx\/politica\/sheinbaum-presente-ix-cumbre-celac-honduras-20250409-754220.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mandataria convers\u00f3 con su hom\u00f3logo, adem\u00e1s estuvo acompa\u00f1ada de L\u00e1zaro C\u00e1rdenas, jefe de la Oficina de la Presidencia; Raquel Serur, subsecretaria para Am\u00e9rica Latina y el Caribe. Tomado de El Economista Redacci\u00f3n Mi\u00e9rcoles 9 de abril de 2025 El d\u00eda de hoy la presidenta Claudia Sheinbaum viaj\u00f3 a Honduras para ser parte de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,115,105],"tags":[],"class_list":{"0":"post-26952","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mexico","8":"category-politica","9":"category-principal"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=26952"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26952\/revisions"}],"predecessor-version":[{"id":26954,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26952\/revisions\/26954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/26953"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=26952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=26952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=26952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}