{"id":26836,"date":"2025-04-07T21:46:17","date_gmt":"2025-04-08T04:46:17","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=26836"},"modified":"2025-04-07T21:46:20","modified_gmt":"2025-04-08T04:46:20","slug":"localizan-una-bomba-en-prepa-5-de-la-unam-y-desalojan-a-estudiantes","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/04\/07\/localizan-una-bomba-en-prepa-5-de-la-unam-y-desalojan-a-estudiantes\/","title":{"rendered":"Localizan una bomba en Prepa 5 de la UNAM y desalojan a estudiantes"},"content":{"rendered":"\n<p><strong>El artefacto fue localizado por alumnos y se realiz\u00f3 la b\u00fasqueda de otros dos<\/strong><\/p>\n\n\n\n<p>Tomado de Infobae<\/p>\n\n\n\n<p>Mariana L. Mart\u00ednez<\/p>\n\n\n\n<p>Lunes 7 de abril de 2025<\/p>\n\n\n\n<p>Las y los estudiantes de la Prepa 5 de la UNAM recibieron la indicaci\u00f3n de salir del plantel por su propia seguridad, ya que hab\u00eda amenaza de bomba.<\/p>\n\n\n\n<p>A su llegada al plantel, el equipo Zorros de personal especializado en desactivaci\u00f3n de artefactos explosivos de la Secretar\u00eda de Seguridad Ciudadana SSC ubic\u00f3 una supuesta bomba y comenz\u00f3 la b\u00fasqueda de otras dos.<\/p>\n\n\n\n<p>El objeto explosivo fue localizado afuera de un cub\u00edculo de trabajo y organizaci\u00f3n estudiantil conocido como e39. Los alumnos entregaron el artefacto a la direcci\u00f3n del plantel.<\/p>\n\n\n\n<p>El desalojo de este plantel de bachillerato de la Universidad Nacional Aut\u00f3noma de M\u00e9xico ocurri\u00f3 despu\u00e9s de las 11:00 horas.<\/p>\n\n\n\n<p>Al menos hasta las 16:00, la direcci\u00f3n de la Prepa 5 de la UNAM no ha realizado alg\u00fan comunicado respecto al suceso.<\/p>\n\n\n\n<p>Esta no es la primera vez en que hay amenaza de alg\u00fan artefacto explosivo en el plantel Jos\u00e9 Vasconcelos, pues en 2020 las autoridades recibieron alertamiento de bomba en la misma escuela.<\/p>\n\n\n\n<p>En su momento se trat\u00f3 de una falsa alarma, de acuerdo con lo que explic\u00f3 la Secretar\u00eda de Gesti\u00f3n Integral de Riesgos y Protecci\u00f3n Civil:<\/p>\n\n\n\n<p>\u201cTras concluir revisi\u00f3n al exterior, interior y zonas estrat\u00e9gicas del plantel escolar; no se localiz\u00f3 alg\u00fan artefacto sospechoso\u201d <\/p>\n\n\n\n<p><strong>https:\/\/www.infobae.com\/mexico\/2025\/04\/07\/localizan-una-bomba-en-prepa-5-de-la-unam-y-desalojan-a-estudiantes<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El artefacto fue localizado por alumnos y se realiz\u00f3 la b\u00fasqueda de otros dos Tomado de Infobae Mariana L. Mart\u00ednez Lunes 7 de abril de 2025 Las y los estudiantes de la Prepa 5 de la UNAM recibieron la indicaci\u00f3n de salir del plantel por su propia seguridad, ya que hab\u00eda amenaza de bomba. A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,105,113],"tags":[],"class_list":{"0":"post-26836","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mexico","8":"category-principal","9":"category-seguridad"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=26836"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26836\/revisions"}],"predecessor-version":[{"id":26838,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26836\/revisions\/26838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/26837"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=26836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=26836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=26836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}