{"id":26787,"date":"2025-04-06T17:05:51","date_gmt":"2025-04-07T00:05:51","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=26787"},"modified":"2025-04-06T17:05:54","modified_gmt":"2025-04-07T00:05:54","slug":"pega-caida-de-bolsas-a-los-ahorros-de-dos-de-cada-tres-hogares-estadunidenses","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/04\/06\/pega-caida-de-bolsas-a-los-ahorros-de-dos-de-cada-tres-hogares-estadunidenses\/","title":{"rendered":"Pega ca\u00edda de bolsas a los ahorros de dos de cada tres hogares estadunidenses"},"content":{"rendered":"\n<p>Tomado de La Jornada<\/p>\n\n\n\n<p>Clara Zepeda<\/p>\n\n\n\n<p>Domingo 6 de abril de 2025<\/p>\n\n\n\n<p>Dos de cada tres hogares en Estados Unidos que poseen alg\u00fan activo burs\u00e1til \u2013fondos conjuntos, cuentas de jubilaci\u00f3n o individuales\u2013 han sufrido una fuerte erosi\u00f3n de su riqueza ante el desplome de los mercados accionarios en Estados Unidos, debido a la guerra comercial que inici\u00f3 el presidente Donald Trump.<\/p>\n\n\n\n<p>En comparaci\u00f3n con otros pa\u00edses, Estados Unidos tiene un alto porcentaje de personas que invierten en la bolsa.<\/p>\n\n\n\n<p>La p\u00e9rdida de alrededor de m\u00e1s de 8 billones de d\u00f3lares en valor de capitalizaci\u00f3n en los mercados accionarios durante las \u00faltimas jornadas, llev\u00f3 a que 2025 sea el segundo peor arranque de una administraci\u00f3n desde 1937; s\u00f3lo en 2001 se tuvo un peor inicio de gobierno (estallido de la burbuja de las puntocom).<\/p>\n\n\n\n<p>Lo que m\u00e1s odian los mercados es la incertidumbre. \u201cEl tema de los aranceles de Trump le est\u00e1 pegando a los mercados accionarios y eso s\u00ed importa mucho al mandatario. No olvidemos que la bolsa de valores es un mercado muy popular, porque participan muchos fondos de pensiones y una cantidad creciente de ciudadanos promedio; entonces, ca\u00eddas tan fuertes como se han visto representan una erosi\u00f3n de riqueza para los hogares y esa fue una de las razones que hicieron a muchos pensar que Trump en alg\u00fan momento se iba a echar para atr\u00e1s.<\/p>\n\n\n\n<p>No s\u00f3lo est\u00e1 el tema de los aranceles y su futuro impacto en los precios y la inflaci\u00f3n, sino el efecto inmediato en la bolsa y otros mercados financieros que son relevantes para el estadunidense promedio. El problema es que no queda claro d\u00f3nde se va a detener, destac\u00f3 Alexis Milo, analista independiente.<\/p>\n\n\n\n<p>Explic\u00f3 que quiz\u00e1s darse un tiro en el pie no es que al estadunidense promedio le salga m\u00e1s caro un autom\u00f3vil o un refrigerador, o que se piense que entre el tipo de cambio y el margen del exportador mexicano se pudiera absorber el golpe de los aranceles y que de alguna manera el problema de la inflaci\u00f3n no sea grave; pero lo que se ha visto con los mercados s\u00ed, porque al estadunidense promedio le llega su estado de cuenta de inversi\u00f3n y ve que tiene muchos d\u00f3lares menos que ten\u00eda el mes anterior (minusval\u00edas).<\/p>\n\n\n\n<p>De acuerdo con Carlos Ponce, socio fundador y director general de SNX, habr\u00e1 negociaciones posteriores al 2 de abril, por lo que no se descarta que la volatilidad se mantenga.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.jornada.com.mx\/noticia\/2025\/04\/06\/economia\/pega-caida-de-bolsas-a-los-ahorros-de-dos-de-cada-tres-hogares-estadunidenses\">https:\/\/www.jornada.com.mx\/noticia\/2025\/04\/06\/economia\/pega-caida-de-bolsas-a-los-ahorros-de-dos-de-cada-tres-hogares-estadunidenses<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tomado de La Jornada Clara Zepeda Domingo 6 de abril de 2025 Dos de cada tres hogares en Estados Unidos que poseen alg\u00fan activo burs\u00e1til \u2013fondos conjuntos, cuentas de jubilaci\u00f3n o individuales\u2013 han sufrido una fuerte erosi\u00f3n de su riqueza ante el desplome de los mercados accionarios en Estados Unidos, debido a la guerra comercial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[114,7,105],"tags":[],"class_list":{"0":"post-26787","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"category-internacional","9":"category-principal"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=26787"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26787\/revisions"}],"predecessor-version":[{"id":26789,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26787\/revisions\/26789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/26788"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=26787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=26787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=26787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}