{"id":26581,"date":"2025-04-01T22:38:28","date_gmt":"2025-04-02T05:38:28","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=26581"},"modified":"2025-04-01T22:38:31","modified_gmt":"2025-04-02T05:38:31","slug":"carteles-usan-drones-hechos-a-la-medida-para-traficar-droga-a-eu-cargan-hasta-100-kilos","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/04\/01\/carteles-usan-drones-hechos-a-la-medida-para-traficar-droga-a-eu-cargan-hasta-100-kilos\/","title":{"rendered":"C\u00e1rteles usan drones hechos a la medida para traficar droga a EU; cargan hasta 100 kilos"},"content":{"rendered":"\n<p><strong>Autoridades estadounidenses advierten que el CJNG y el De Sinaloa fabrican estos aparatos teledirigidos con capacidad de hasta 100 kilos<\/strong><\/p>\n\n\n\n<p>Informaci\u00f3n de El Universal<\/p>\n\n\n\n<p>Redacci\u00f3n<\/p>\n\n\n\n<p>Martes 1 de abril de 2025<\/p>\n\n\n\n<p>Los c\u00e1rteles mexicanos dejaron de importar drones y ahora se inclinan por aparatos de fabricaci\u00f3n local, hechos a la medida, con m\u00e1s capacidad de carga para transportar hasta 100 kilogramos de drogas como fentaniloo metanfetamina a territorio de Estados Unidos.<\/p>\n\n\n\n<p>La Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP, por sus siglas en ingl\u00e9s) de Estados Unidos report\u00f3 a la Junta Internacional de Fiscalizaci\u00f3n de Estupefacientes (JIFE) para su informe 2024 que los grupos criminales mexicanos sol\u00edan operar en la frontera norte aeronaves teledirigidas de corto alcance y con baja capacidad de carga, de unos cuantos kilogramos.<\/p>\n\n\n\n<p>Sin embargo, \u201cse tienen noticias de que los traficantes se inclinan ahora por sistemas de fabricaci\u00f3n local y hechos a la medida. Al parecer, los drones fabricados a medida pueden transportar hasta 100 kilogramos\u201d, subray\u00f3.<\/p>\n\n\n\n<p>En 2010, autoridades mexicanas alertaron por primera vez a Estados Unidos que los c\u00e1rteles comenzaban a usar en la frontera sistemas de aeronaves teledirigidas; las primeras detectadas procedentes de M\u00e9xico eran importadas, de acuerdo con la CBP.<\/p>\n\n\n\n<p>Entre 2012 y 2014, Estados Unidos detect\u00f3 150 drones cruzando la frontera con M\u00e9xico con paquetes de drogas, mismos que fueron neutralizados por sus agentes de seguridad en la regi\u00f3n. No obstante, en 2022, la Oficina de Aduanas y Protecci\u00f3n Fronteriza report\u00f3 al menos 10 mil incursiones con aeronaves teledirigidas en la zona de R\u00edo Grande, entre los l\u00edmites de los estados de Tamaulipas con Texas, considerada un importante corredor para el tr\u00e1fico de drogas a Estados Unidos.<\/p>\n\n\n\n<p>Seg\u00fan la CBP, M\u00e9xico, Colombia y Estados Unidos son algunos de los pa\u00edses que han comunicado incidentes en los que se utilizaron drones para el tr\u00e1fico de drogas, principalmente cerca de las fronteras o de centros penitenciarios.<\/p>\n\n\n\n<p>Los drones utilizados por los c\u00e1rteles, como los De Sinaloa y Jalisco Nueva Generaci\u00f3n, est\u00e1n equipados con tecnolog\u00eda de los sistemas mundiales de navegaci\u00f3n por sat\u00e9lite, lo que les permite programar con antelaci\u00f3n los lugares concretos de aterrizaje y garantizar una entrega segura y precisa de los paquetes de droga que intentan llevar a la Uni\u00f3n Americana.<\/p>\n\n\n\n<p>Pese a que los grupos criminales recurren cada vez m\u00e1s al uso de drones para traficar drogas en la frontera entre M\u00e9xico y Estados Unidos, la JIFE asegur\u00f3 que las cantidades que se transportan con las aeronaves teledirigidas \u201csiguen siendo insignificantes\u201d en comparaci\u00f3n con otros modos de transporte m\u00e1s tradicionales y consolidados, como los contenedores de carga mar\u00edtima, terrestre y a\u00e9rea, as\u00ed como los servicios de mensajer\u00eda urgente.<\/p>\n\n\n\n<p>\u201cAunque esta tendencia sigue siendo en gran medida un fen\u00f3meno regional, los avances tecnol\u00f3gicos, el aumento de la capacidad, el abaratamiento de los costos y la mejora de las estrategias operacionales tal vez den lugar a un incremento en el futuro de las cantidades totales de drogas traficadas a trav\u00e9s de esos sistemas\u201d, admiti\u00f3.<\/p>\n\n\n\n<p>Para responder a estas amenazas, la JIFE recomend\u00f3 a los gobiernos de M\u00e9xico, Estados Unidos y Colombia realizar acciones legislativas o nuevas contramedidas, como las tecnolog\u00edas de detecci\u00f3n por radar y de geovallas, que permiten interceptar los drones utilizados para el tr\u00e1fico de drogas.<\/p>\n\n\n\n<p>Por ejemplo, se\u00f1al\u00f3 la Organizaci\u00f3n de Naciones Unidas (ONU), la Uni\u00f3n Europea (UE) elabora un amplio marco regulador para combatir las actividades ilegales relacionadas con los sistemas de aeronaves teledirigidas: \u201cNo obstante, en general las leyes y reglamentaciones nacionales no suelen contener disposiciones relativas al tr\u00e1fico de drogas mediante esos sistemas\u201d, lament\u00f3.<\/p>\n\n\n\n<p><strong>Aumenta uso de \u201cnarcosubmarinos\u201d<\/strong><\/p>\n\n\n\n<p>En su informe 2024, la Junta Internacional de Fiscalizaci\u00f3n de Estupefacientes tambi\u00e9n alert\u00f3 que los c\u00e1rteles de la droga, principalmente los De Sinaloa y Jalisco Nueva Generaci\u00f3n, aumentaron el uso de \u201cnarcosubmarinos\u201d para el tr\u00e1fico de estupefacientes por mar en los \u00faltimos 10 a\u00f1os.<\/p>\n\n\n\n<p>\u201cEl tr\u00e1fico de coca\u00edna de Am\u00e9rica del Sur a M\u00e9xico, y de M\u00e9xico a Estados Unidos est\u00e1 controlado en buena medida por los c\u00e1rteles mexicanos De Sinaloa y Jalisco Nueva Generaci\u00f3n (CJNG).<\/p>\n\n\n\n<p>Esos c\u00e1rteles obtienen remesas de varias toneladas de coca\u00edna en polvo y base de coca\u00edna de traficantes sudamericanos, que luego las transportan clandestinamente \u2014bien por rutas terrestres y v\u00edas acu\u00e1ticas costeras de Centroam\u00e9rica, bien por mar hasta islas caribe\u00f1as como Puerto Rico y Rep\u00fablica Dominicana\u2014 y, por \u00faltimo, las introducen en Estados Unidos. Una vez en ese pa\u00eds, la sustancia es distribuida por grupos delictivos locales y bandas callejeras\u201d, puntualiz\u00f3 el reporte de la JIFE.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/carteles-usan-drones-hechos-a-la-medida-para-traficar-droga-a-eu-cargan-hasta-100-kilos\">https:\/\/www.eluniversal.com.mx\/nacion\/carteles-usan-drones-hechos-a-la-medida-para-traficar-droga-a-eu-cargan-hasta-100-kilos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades estadounidenses advierten que el CJNG y el De Sinaloa fabrican estos aparatos teledirigidos con capacidad de hasta 100 kilos Informaci\u00f3n de El Universal Redacci\u00f3n Martes 1 de abril de 2025 Los c\u00e1rteles mexicanos dejaron de importar drones y ahora se inclinan por aparatos de fabricaci\u00f3n local, hechos a la medida, con m\u00e1s capacidad de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,113],"tags":[],"class_list":{"0":"post-26581","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mexico","8":"category-seguridad"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=26581"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26581\/revisions"}],"predecessor-version":[{"id":26583,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26581\/revisions\/26583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/26582"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=26581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=26581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=26581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}