{"id":26554,"date":"2025-04-01T21:43:43","date_gmt":"2025-04-02T04:43:43","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=26554"},"modified":"2025-04-01T21:43:46","modified_gmt":"2025-04-02T04:43:46","slug":"cientifico-mexicano-del-ipn-innova-en-el-diagnostico-de-cancer-de-mama-con-tecnicas-3d","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/04\/01\/cientifico-mexicano-del-ipn-innova-en-el-diagnostico-de-cancer-de-mama-con-tecnicas-3d\/","title":{"rendered":"Cient\u00edfico mexicano del IPN innova en el diagn\u00f3stico de c\u00e1ncer de mama con t\u00e9cnicas 3D"},"content":{"rendered":"\n<p><strong>A trav\u00e9s de materiales fotopolim\u00e9ricos, esta tecnolog\u00eda desarrollada en el Instituto Polit\u00e9cnico Nacional representa una nueva herramienta para la detecci\u00f3n y tratamiento oportuno de la enfermedad oncol\u00f3gica<\/strong><\/p>\n\n\n\n<p>Tomado de Infobae<\/p>\n\n\n\n<p>Mariana \u00c1lvarez Torres<\/p>\n\n\n\n<p>Lunes 31 de marzo de 2025<\/p>\n\n\n\n<p>El modelo 3D del doctor Juan Alfonso Beltr\u00e1n ser\u00e1 una herramienta clave en ex\u00e1menes m\u00e9dicos m\u00e1s efectivos para la detecci\u00f3n temprana de tumores. (Instituto Polit\u00e9cnico Nacional, IPN)<\/p>\n\n\n\n<p>Juan Alfonso Beltr\u00e1n Fern\u00e1ndez, investigador del Instituto Polit\u00e9cnico Nacional (IPN), dise\u00f1\u00f3 un m\u00e9todo que utiliza modelos tridimensionales impresos en resina para recrear con precisi\u00f3n las estructuras internas de las mamas, lo cual tiene el objetivo de mejorar la detecci\u00f3n temprana de tumores y optimizar la planeaci\u00f3n quir\u00fargica, as\u00ed como la formaci\u00f3n m\u00e9dica y la concientizaci\u00f3n del paciente.<\/p>\n\n\n\n<p>El c\u00e1ncer de mama es la principal causa de muerte por c\u00e1ncer entre las mujeres en M\u00e9xico, con un promedio de 18 fallecimientos diarios, seg\u00fan datos de la Fundaci\u00f3n CIMA. Cada a\u00f1o se diagnostican aproximadamente 30 mil nuevos casos, pero solo un tercio de las pacientes recibe un diagn\u00f3stico en etapas tempranas, lo que reduce significativamente las posibilidades de tratamiento exitoso.<\/p>\n\n\n\n<p>De acuerdo con las estad\u00edsticas, entre el 75 % y el 85 % de los casos podr\u00edan ser curables si se detectaran a tiempo, sin embargo, la realidad es alarmante, pues s\u00f3lo en 2023, se registraron ocho mil 34 muertes por esta enfermedad en mujeres mayores de 20 a\u00f1os.<\/p>\n\n\n\n<p><strong>En qu\u00e9 consiste el modelo tridimensional<\/strong><\/p>\n\n\n\n<p>Fabricado con resina fotopolim\u00e9rica, su implementaci\u00f3n apoyar\u00e1 a procedimientos m\u00e9dicos avanzados.<\/p>\n\n\n\n<p>El m\u00e9todo desarrollado por el doctor Beltr\u00e1n Fern\u00e1ndez utiliza im\u00e1genes obtenidas de tomograf\u00edas computarizadas, resonancias magn\u00e9ticas, mastograf\u00edas y ultrasonidos, que son procesadas mediante el software ScanIP a partir del que se &nbsp;genera un archivo estereolitogr\u00e1fico (STL, por sus siglas en ingl\u00e9s) apto para impresi\u00f3n en 3D. Posteriormente, seg\u00fan el procedimiento detallado por el IPN, un visor externo llamado Meshmixer permite manipular y analizar din\u00e1micamente las estructuras de la mama, desde la piel hasta los tejidos internos, vasos, l\u00f3bulos y ganglios.<\/p>\n\n\n\n<p>Fern\u00e1ndez, integrante del nivel II en el Sistema Nacional de Investigadoras e Investigadores (SNII), explic\u00f3 que la impresi\u00f3n en 3D se realiza con resina fotopolim\u00e9rica, un material experimental que, al ser expuesto a un lente polarizador dise\u00f1ado por el propio investigador, intensifica su color en las \u00e1reas donde hay tejido tumoral.<\/p>\n\n\n\n<p>&nbsp;\u201cLa estructura interna de toda la fisiolog\u00eda de la mama se imprime entre un 80 al 100 por ciento de su tama\u00f1o real, este proceso se realiza en aproximadamente 8 o 9 horas\u201d, detall\u00f3 el acad\u00e9mico.<\/p>\n\n\n\n<p>Este detalle de escalas es crucial para identificar posibles anomal\u00edas en etapas iniciales, ya que permite a los especialistas observar con mayor claridad las estructuras internas de la mama, superando las limitaciones de las im\u00e1genes bidimensionales en escala de grises que ofrecen las tomograf\u00edas convencionales. Adem\u00e1s, el polarizador port\u00e1til permite identificar patrones de tonalidades verdes y tornasoladas en las \u00e1reas sospechosas, que podr\u00eda favorecer la decisi\u00f3n del m\u00e9dico en el proceder del tratamiento, como por ejemplo, realizar una biopsia.<\/p>\n\n\n\n<p>El doctor en Biomec\u00e1nica adscrito a la Escuela Superior de Ingenier\u00eda Mec\u00e1nica y El\u00e9ctrica (ESIME) Unidad Zacatenco asegur\u00f3 que esta herramienta tambi\u00e9n tiene un valor educativo si se utiliza en la formaci\u00f3n de m\u00e9dicos en entrenamiento, ayud\u00e1ndoles a comprender mejor la anatom\u00eda y las patolog\u00edas relacionadas con el c\u00e1ncer de mama. De igual manera, lo considera aplicable para la concientizaci\u00f3n de los pacientes, quienes tendr\u00edan una oportunidad visualizar de manera tangible las caracter\u00edsticas de su condici\u00f3n.<\/p>\n\n\n\n<p>Aunque el proyecto a\u00fan est\u00e1 en proceso de validaci\u00f3n hospitalaria, una vez aprobado se planea registrar la patente ante el Instituto Mexicano de la Propiedad Industrial (IMPI). Asimismo, se est\u00e1 evaluando la posibilidad de fabricar los modelos con materiales m\u00e1s flexibles para ampliar su utilidad en la planeaci\u00f3n quir\u00fargica.<\/p>\n\n\n\n<p>Los avances del proyecto ser\u00e1n presentados en la 18th Conferencia Internacional de Ingenier\u00eda Computacional Avanzada y Experimentaci\u00f3n (ACEX), que se llevar\u00e1 a cabo en junio de 2025 en N\u00e1poles, Italia, y seg\u00fan inform\u00f3 el IPN, los resultados de esta investigaci\u00f3n ser\u00e1n publicados como un cap\u00edtulo de libro.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es el c\u00e1ncer de mama?<\/strong><\/p>\n\n\n\n<p>La prevenci\u00f3n, la detecci\u00f3n temprana y el tratamiento oportuno son claves fundamentales en la lucha contra el c\u00e1ncer de mama.<\/p>\n\n\n\n<p>La Sociedad Estadounidense contra el C\u00e1ncer (ACS, por sus siglas en ingl\u00e9s), define al c\u00e1ncer de mama, tambi\u00e9n conocido como c\u00e1ncer mamario o de seno, como una enfermedad que se origina en los tejidos de esta parte del cuerpo y puede afectar a uno o a ambos. Este tipo de c\u00e1ncer se desarrolla cuando las c\u00e9lulas comienzan a crecer de manera descontrolada, lo que puede llevar a su propagaci\u00f3n a trav\u00e9s de la sangre o el sistema linf\u00e1tico hacia otras \u00e1reas del organismo.<\/p>\n\n\n\n<p>La ACS detalla que existen diversos tipos de c\u00e1ncer de mama, los cuales se clasifican seg\u00fan las c\u00e9lulas espec\u00edficas que resultan afectadas. La mayor\u00eda de los casos corresponden a carcinomas, un tipo de c\u00e1ncer que se forma en las c\u00e9lulas epiteliales, entre los cuales, los m\u00e1s comunes son el carcinoma ductal in situ (DCIS) y el carcinoma invasivo, ambos considerados adenocarcinomas debido a que se originan en las c\u00e9lulas glandulares de los conductos galact\u00f3foros o en los l\u00f3bulos, que son las gl\u00e1ndulas encargadas de producir leche.<\/p>\n\n\n\n<p>Adem\u00e1s de los carcinomas, la Sociedad Estadounidense contra el C\u00e1ncer se\u00f1ala que existen otros tipos de c\u00e1ncer que pueden desarrollarse en el seno, como el angiosarcoma o el sarcoma, sin embargo, estos no se consideran c\u00e1nceres mamarios propiamente, ya que se originan en c\u00e9lulas que no pertenecen al tejido mamario.<\/p>\n\n\n\n<p>La clasificaci\u00f3n de los c\u00e1nceres de mama tambi\u00e9n se realiza en funci\u00f3n de determinadas prote\u00ednas o genes que las c\u00e9lulas tumorales producen, entre las que se encuentran los receptores de estr\u00f3geno, los receptores de progesterona y la prote\u00edna HER2. La presencia o ausencia de estas mol\u00e9culas en las c\u00e9lulas cancerosas influye en el diagn\u00f3stico y en las opciones de tratamiento disponibles como cirug\u00eda, quimioterapia, radioterapia, terapia hormonal o tratamientos dirigidos.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.infobae.com\/mexico\/2025\/03\/31\/cientifico-mexicano-del-ipn-innova-en-el-diagnostico-de-cancer-de-mama-con-tecnicas-3d\">https:\/\/www.infobae.com\/mexico\/2025\/03\/31\/cientifico-mexicano-del-ipn-innova-en-el-diagnostico-de-cancer-de-mama-con-tecnicas-3d<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de materiales fotopolim\u00e9ricos, esta tecnolog\u00eda desarrollada en el Instituto Polit\u00e9cnico Nacional representa una nueva herramienta para la detecci\u00f3n y tratamiento oportuno de la enfermedad oncol\u00f3gica Tomado de Infobae Mariana \u00c1lvarez Torres Lunes 31 de marzo de 2025 El modelo 3D del doctor Juan Alfonso Beltr\u00e1n ser\u00e1 una herramienta clave en ex\u00e1menes m\u00e9dicos m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[10,3,18],"tags":[],"class_list":{"0":"post-26554","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciencia","8":"category-mexico","9":"category-tecnologia"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=26554"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26554\/revisions"}],"predecessor-version":[{"id":26556,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26554\/revisions\/26556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/26555"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=26554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=26554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=26554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}