{"id":26012,"date":"2025-03-17T23:43:48","date_gmt":"2025-03-18T06:43:48","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=26012"},"modified":"2025-03-17T23:50:12","modified_gmt":"2025-03-18T06:50:12","slug":"campanon-carronero-norona-usa-redes-del-senado-para-arremeter-contra-la-derecha-por-teuchitlan","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/03\/17\/campanon-carronero-norona-usa-redes-del-senado-para-arremeter-contra-la-derecha-por-teuchitlan\/","title":{"rendered":"\u201cCampa\u00f1\u00f3n carro\u00f1ero\u201d: Noro\u00f1a usa redes del Senado para arremeter contra la \u201cderecha\u201d por Teuchitl\u00e1n"},"content":{"rendered":"\n<p><strong>\u201cQuieren utilizar ese dolor y sufrimiento para buscar golpear a nuestro gobierno y a nuestro movimiento\u201d, dijo el morenista.<\/strong><\/p>\n\n\n\n<p>Tomado de Proceso<\/p>\n\n\n\n<p>Juan Carlos Cort\u00e9s<\/p>\n\n\n\n<p>Lunes 17 de marzo de 2025<\/p>\n\n\n\n<p>CIUDAD DE M\u00c9XICO (apro).- Luego de que el pasado 15 de marzo el senador morenista Gerardo Fern\u00e1ndez Noro\u00f1a cuestionara que los zapatos encontrados en el rancho Izaguirre de Teuchitl\u00e1n, Jalisco, fueran de personas desaparecidas, este lunes dio un mensaje desde las redes sociales del Senado, en donde acus\u00f3 que \u201cla derecha\u201d ha hecho una campa\u00f1a carro\u00f1era sobre el tema para golpear al gobierno de Claudia Sheinbaum.<\/p>\n\n\n\n<p>En un video publicado en las redes de la C\u00e1mara alta, el presidente de la Mesa Directiva se\u00f1al\u00f3 que la oposici\u00f3n critica el caso como una manera ruin, ya que quieren utilizar el dolor y sufrimiento para \u201cgolpear\u201d al movimiento sin tener inter\u00e9s en ayudar.<\/p>\n\n\n\n<p>&nbsp;\u201cEs un tema que mucho nos duele, y que es perverso de la derecha que pretenda plantear que somos responsables, o que somos insensibles a esta dificultad. Han hecho, en el caso de Teuchitl\u00e1n, Jalisco, un campa\u00f1\u00f3n verdaderamente carro\u00f1ero, es la palabra, para golpear al gobierno de la compa\u00f1era presidenta Claudia Sheinbaum Pardo.<\/p>\n\n\n\n<p>\u201cEs una manera ruin, es una manera infame, no tienen ning\u00fan inter\u00e9s en colaborar, en coadyuvar, en auxiliar, en respaldar o criticar seriamente cualquier acci\u00f3n que se estuviese realizando, sino quieren medrar, quieren utilizar ese dolor y sufrimiento para buscar golpear a nuestro gobierno y a nuestro movimiento\u201d, detall\u00f3.<\/p>\n\n\n\n<p>En el video, el senador afirm\u00f3 que la verdad saldr\u00e1 a la luz y la investigaci\u00f3n arrojar\u00e1 lo que pas\u00f3 en Teuchitl\u00e1n, Jalisco, y resalt\u00f3 que no habr\u00e1 impunidad.<\/p>\n\n\n\n<p>Para finalizar reafirm\u00f3 su respaldo a la presidenta Claudia Sheinbaum y manifest\u00f3 su solidaridad con todas personas y familias que buscan a sus seres queridos.<\/p>\n\n\n\n<p><strong>&nbsp;\u201cMontados en la tragedia\u201d<\/strong><\/p>\n\n\n\n<p>El pasado 15 de marzo, durante su charla en redes sociales, el legislador afirm\u00f3 que los medios y la derecha se \u201cmontaron\u201d en la tragedia y cuestion\u00f3 que los zapatos encontrados fueran de personas desaparecidas<\/p>\n\n\n\n<p>\u201cF\u00edjense que el tema del rancho de Teuchitl\u00e1n, pues otra vez los medios y la derecha est\u00e1n montados en la tragedia, pero yo no hab\u00eda pensado. A ver, como dicen los abogados, aceptando sin conceder que las presunciones que dicen sean ciertas, pues son presunciones.<\/p>\n\n\n\n<p>\u201cHay doscientos zapatos ah\u00ed, s\u00ed, s\u00ed, s\u00ed, pero qui\u00e9n dice que esos zapatos son de personas desaparecidas, es lo que se viene contando. Es cierto, no tengo por qu\u00e9 dudarlo, pero tampoco, hay una investigaci\u00f3n en proceso. Los medios locales, aqu\u00ed es un asunto nacional, hombres, se van con la misma l\u00ednea. Cuando digo es un asunto nacional no es que sea un asunto de inter\u00e9s nacional, que obvio lo es, sino que se van con la l\u00ednea del golpeteo\u201d, resalt\u00f3.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.proceso.com.mx\/nacional\/politica\/2025\/3\/17\/campanon-carronero-norona-usa-redes-del-senado-para-arremeter-contra-la-derecha-por-teuchitlan-347574.html\">https:\/\/www.proceso.com.mx\/nacional\/politica\/2025\/3\/17\/campanon-carronero-norona-usa-redes-del-senado-para-arremeter-contra-la-derecha-por-teuchitlan-347574.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cQuieren utilizar ese dolor y sufrimiento para buscar golpear a nuestro gobierno y a nuestro movimiento\u201d, dijo el morenista. Tomado de Proceso Juan Carlos Cort\u00e9s Lunes 17 de marzo de 2025 CIUDAD DE M\u00c9XICO (apro).- Luego de que el pasado 15 de marzo el senador morenista Gerardo Fern\u00e1ndez Noro\u00f1a cuestionara que los zapatos encontrados en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,115],"tags":[],"class_list":{"0":"post-26012","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mexico","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=26012"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26012\/revisions"}],"predecessor-version":[{"id":26014,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/26012\/revisions\/26014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/26013"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=26012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=26012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=26012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}