{"id":25652,"date":"2025-03-10T00:20:40","date_gmt":"2025-03-10T07:20:40","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=25652"},"modified":"2025-03-10T00:20:41","modified_gmt":"2025-03-10T07:20:41","slug":"limpian-pintas-donde-mujeres-manifestantes-expresaron-desacuerdos-durante-el-8m-en-hermosillo","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/03\/10\/limpian-pintas-donde-mujeres-manifestantes-expresaron-desacuerdos-durante-el-8m-en-hermosillo\/","title":{"rendered":"Limpian \u2018pintas\u2019 donde mujeres manifestantes expresaron desacuerdos durante el 8M en Hermosillo"},"content":{"rendered":"\n<p><strong>Trabajadores del Supremo Tribunal de Justicia acudieron a temprana hora a limpiar vestigios de la marcha realizada por mujeres el s\u00e1bado 8 de marzo en la capital de Sonora<\/strong><\/p>\n\n\n\n<p>Con informaci\u00f3n de N+ Noticias<\/p>\n\n\n\n<p>Redacci\u00f3n<\/p>\n\n\n\n<p>Domingo 9 de marzo de 2025<\/p>\n\n\n\n<p>Desde temprana hora comenzaron a limpiar los vestigios de la marcha por el 8M; las pintas que habr\u00edan dejado manifestantes para expresar sus desacuerdos y solicitudes ente el Poder Judicial del Estado han sido eliminadas.<\/p>\n\n\n\n<p>Trabajadores de Infraestructura del Supremo Tribunal de Justicia trabajaron desde las 6:00 de la ma\u00f1ana en la limpieza y pintura de la fachada del edificio.<\/p>\n\n\n\n<p>Mientras tanto, en otros puntos de la Plaza Bicentenario todav\u00eda prevalec\u00edan algunas de las pintas se\u00f1alando presuntos casos de abuso y violencia hacia las mujeres.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.nmas.com.mx\/sonora\/limpian-pintas-realizadas-por-mujeres-en-marcha-8m-en-hermosillo-sonora\">https:\/\/www.nmas.com.mx\/sonora\/limpian-pintas-realizadas-por-mujeres-en-marcha-8m-en-hermosillo-sonora<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajadores del Supremo Tribunal de Justicia acudieron a temprana hora a limpiar vestigios de la marcha realizada por mujeres el s\u00e1bado 8 de marzo en la capital de Sonora Con informaci\u00f3n de N+ Noticias Redacci\u00f3n Domingo 9 de marzo de 2025 Desde temprana hora comenzaron a limpiar los vestigios de la marcha por el 8M; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[8,115],"tags":[],"class_list":{"0":"post-25652","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hermosillo","8":"category-politica"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/25652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=25652"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/25652\/revisions"}],"predecessor-version":[{"id":25654,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/25652\/revisions\/25654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/25653"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=25652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=25652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=25652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}