{"id":25403,"date":"2025-03-03T23:49:04","date_gmt":"2025-03-04T06:49:04","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=25403"},"modified":"2025-03-03T23:49:06","modified_gmt":"2025-03-04T06:49:06","slug":"carteles-gobiernan-mexico-insiste-la-casa-blanca-trump-explora-todas-las-opciones","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2025\/03\/03\/carteles-gobiernan-mexico-insiste-la-casa-blanca-trump-explora-todas-las-opciones\/","title":{"rendered":"C\u00e1rteles gobiernan M\u00e9xico, insiste la Casa Blanca; Trump &#8220;explora todas las opciones&#8221;"},"content":{"rendered":"\n<p><strong>La crisis fronteriza no es s\u00f3lo un problema de seguridad nacional sino una \u201cmisi\u00f3n militar\u201d, afirma Stephen Miller, subjefe de gabinete y asesor de seguridad interior de la Casa Blanca.<\/strong><\/p>\n\n\n\n<p>Tomado de Proceso<\/p>\n\n\n\n<p>Redacci\u00f3n<\/p>\n\n\n\n<p>Lunes 3 de marzo de 2025<\/p>\n\n\n\n<p>CIUDAD DE M\u00c9XICO (apro).- Los c\u00e1rteles criminales controlan y gobiernan el territorio en M\u00e9xico y representan una amenaza continua, sostenida y terrible para Estados Unidos, afirm\u00f3 este lunes Stephen Miller, subjefe de gabinete del gobierno de Donald Trump.<\/p>\n\n\n\n<p>&#8220;El gobierno estadunidense, bajo el liderazgo del presidente Trump, seguir\u00e1 explorando todas las opciones necesarias para hacer frente a esa terrible amenaza&#8221;, dijo a reporteros que lo entrevistaron en la Casa Blanca.<\/p>\n\n\n\n<p>El tambi\u00e9n asesor de seguridad interior asegur\u00f3 que la Bah\u00eda de Guant\u00e1namo se ha convertido en un pilar del plan del gobierno para lidiar con &#8220;extranjeros criminales de alta amenaza&#8221;.<\/p>\n\n\n\n<p>&nbsp;Asimismo subray\u00f3 que la crisis fronteriza no es s\u00f3lo un problema de seguridad nacional sino una \u201cmisi\u00f3n militar\u201d en toda regla dirigida a organizaciones ahora formalmente designadas como amenazas terroristas extranjeras, en referencia a los c\u00e1rteles mexicanos.<\/p>\n\n\n\n<p>Miller destac\u00f3 que esta clasificaci\u00f3n significa que el gobierno de Trump \u201cllevar\u00e1 a cabo operaciones de seguridad cooperativas entre las fuerzas del orden y las fuerzas armadas\u201d para eliminar estas amenazas de las comunidades estadounidenses.<\/p>\n\n\n\n<p>El funcionario elogi\u00f3 la &#8220;reducci\u00f3n del 95% en los cruces&#8221; de migrantes luego del despliegue de militares en la frontera y la aplicaci\u00f3n de &#8220;nuevas estrategias\u201d contra los c\u00e1rteles y el contrabando.<\/p>\n\n\n\n<p>\u201cNunca encontrar\u00e1 un ejemplo de ninguna amenaza a las fuerzas del orden o a la seguridad nacional en el que se haya logrado un cambio tan r\u00e1pido de enfoque, estrategia y resultados\u201d, destac\u00f3 Miller.<\/p>\n\n\n\n<p>En una evaluaci\u00f3n escalofriante de los detenidos en Guant\u00e1namo, Miller describi\u00f3 a individuos tan peligrosos que &#8220;si estuvieran tan cerca como estamos nosotros ahora, y tuvieran la capacidad de agarrar un objeto afilado, matar\u00edan a la persona que est\u00e1 a esa distancia en medio segundo&#8221;. Explic\u00f3 que sin un control f\u00edsico constante, &#8220;les das un par de anteojos, romper\u00edan un pedazo del anteojos y apu\u00f1alar\u00edan a alguien directamente en el cuello&#8221;.<\/p>\n\n\n\n<p>De cara al discurso del Estado de la Uni\u00f3n de ma\u00f1ana por la noche, Miller elogi\u00f3 a Trump como &#8220;el mejor orador que hemos tenido en la Oficina Oval&#8221; y caracteriz\u00f3 el primer mes de la administraci\u00f3n como &#8220;logros y logros sin precedentes que han establecido r\u00e9cords y que han hecho de esta la apertura m\u00e1s exitosa de cualquier presidencia que hayamos visto en la historia estadounidense&#8221;.<\/p>\n\n\n\n<p>Miller tambi\u00e9n destac\u00f3 que &#8220;las encuestas p\u00fablicas muestran que los estadounidenses apoyan abrumadoramente el enfoque del presidente Trump en la guerra en Ucrania y su esfuerzo por poner fin a los combates, a un acuerdo pac\u00edfico y al derramamiento de sangre&#8221;, al tiempo que contrast\u00f3 esto con &#8220;las incre\u00edbles cifras del presidente Biden sobre Ucrania y la pol\u00edtica de guerra eterna&#8221;.<\/p>\n\n\n\n<p>A pesar de los avances significativos en la frontera, Miller advirti\u00f3 que &#8220;los c\u00e1rteles criminales controlan y gobiernan&#8230; el territorio en M\u00e9xico y representan una amenaza continua, sostenida y terrible para los Estados Unidos&#8221;. En quiz\u00e1s la declaraci\u00f3n m\u00e1s siniestra de la sesi\u00f3n informativa, concluy\u00f3 que &#8220;el gobierno estadounidense bajo el liderazgo del presidente Trump seguir\u00e1 explorando todas las opciones necesarias para hacer frente a esa terrible amenaza&#8221;, lo que sugiere que es posible que se adopten medidas a\u00fan m\u00e1s dr\u00e1sticas.<\/p>\n\n\n\n<p>Este informe exclusivo de la Casa Blanca proporciona una visi\u00f3n sin precedentes de la estrategia de seguridad nacional de la administraci\u00f3n y prepara el escenario para lo que promete ser un discurso trascendental sobre el Estado de la Uni\u00f3n ma\u00f1ana por la noche.<\/p>\n\n\n\n<p>En la v\u00edspera del discurso sobre el Estado de la Uni\u00f3n que pronunciar\u00e1 el presidente, Miller elogi\u00f3 a Trump como &#8220;el mejor orador que hemos tenido en la Oficina Oval&#8221; y caracteriz\u00f3 el primer mes de su gobierno como &#8220;logros y realizaciones sin precedentes que han hecho de esta la apertura m\u00e1s exitosa de cualquier presidencia que hayamos visto en la historia estadunidense&#8221;.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.proceso.com.mx\/nacional\/2025\/3\/3\/carteles-gobiernan-mexico-insiste-la-casa-blanca-trump-explora-todas-las-opciones-346647.html\">https:\/\/www.proceso.com.mx\/nacional\/2025\/3\/3\/carteles-gobiernan-mexico-insiste-la-casa-blanca-trump-explora-todas-las-opciones-346647.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La crisis fronteriza no es s\u00f3lo un problema de seguridad nacional sino una \u201cmisi\u00f3n militar\u201d, afirma Stephen Miller, subjefe de gabinete y asesor de seguridad interior de la Casa Blanca. Tomado de Proceso Redacci\u00f3n Lunes 3 de marzo de 2025 CIUDAD DE M\u00c9XICO (apro).- Los c\u00e1rteles criminales controlan y gobiernan el territorio en M\u00e9xico y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[7,105,113],"tags":[],"class_list":{"0":"post-25403","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"category-principal","9":"category-seguridad"},"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/25403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=25403"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/25403\/revisions"}],"predecessor-version":[{"id":25405,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/25403\/revisions\/25405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/25404"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=25403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=25403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=25403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}