{"id":21802,"date":"2024-12-15T23:32:47","date_gmt":"2024-12-16T06:32:47","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21802"},"modified":"2024-12-16T00:16:54","modified_gmt":"2024-12-16T07:16:54","slug":"rechazan-en-el-congreso-del-estado-ley-de-ingresos-2025-para-hermosillo","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/15\/rechazan-en-el-congreso-del-estado-ley-de-ingresos-2025-para-hermosillo\/","title":{"rendered":"Descartan en el Congreso del Estado Ley de Ingresos 2025 para Hermosillo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>-La propuesta del Ayuntamiento presenta irregularidades e incrementos desproporcionados en multas que afectar\u00e1n severamente a los hermosillenses<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-Hermosillo deber\u00e1 mantener la misma Ley de Ingresos 2024 para el pr\u00f3ximo a\u00f1o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 15 de diciembre del 2024.- El Proyecto de Ley de Ingresos 2025, presentado por el Ayuntamiento de Hermosillo, fue rechazado por las bancadas de MOReNa y aliados, en voz del diputado David Figueroa Ortega, dado que registr\u00f3 una serie de irregularidades e incrementos desproporcionados en multas que afectar\u00e1n severamente a los hermosillenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante un f\u00e9rreo posicionamiento, el coordinador del Grupo Parlamentario del Partido Verde Ecologista de M\u00e9xico (PVEM) en el Congreso del Estado propuso al Pleno no aceptar dicho documento presentado por el gobierno municipal y, de esta manera, Hermosillo mantendr\u00e1 la misma Ley de Ingresos 2024 para el pr\u00f3ximo a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Figueroa Ortega destac\u00f3 que \u201cdel an\u00e1lisis realizado a la totalidad de los proyectos presentados, esta comisi\u00f3n se percat\u00f3 que, en el caso particular de Ayuntamiento de Hermosillo, con fecha del 29 de diciembre del 2024 se present\u00f3 un anteproyecto de Ley de Ingresos que evidenciaba claramente una serie de discrepancia presentadas en las mesas de trabajo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estableci\u00f3 que se pudo apreciar que no contaba con el proyecto aprobado en Cabildo, incluso, dicha precisi\u00f3n fue confirmada con el Oficio de fecha 13 de diciembre del 2024 en que el secretario del Ayuntamiento reconoci\u00f3 que se debi\u00f3 a un \u201cerror involuntario\u201d, lo que con fundamento en el Art\u00edculo 181 de la Ley de Gobierno y Administraci\u00f3n Municipal permiti\u00f3 a la soberan\u00eda contar con elementos suficientes para no aprobar la propuesta realizada por el Ayuntamiento para el Ejercicio Fiscal del 2025 y dejar en vigor la del actual a\u00f1o 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta propuesta fue aprobada por mayor\u00eda en el Pleno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las diputadas Elia Sahara Sallard Hern\u00e1ndez (Morena) y Gabriela Danitza F\u00e9lix Boj\u00f3rquez (MC) presentaron el dictamen de la Comisi\u00f3n de Hacienda que autoriz\u00f3 al municipio de Hermosillo a refinanciar o reestructurar su deuda p\u00fablica de largo plazo negando, al mismo tiempo, la contrataci\u00f3n de una nueva l\u00ednea de cr\u00e9dito para obras prioritarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>APRUEBAN LEYES Y PRESUPUESTOS DE INGRESOS DEL RESTO DE LOS AYUNTAMIENTOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Congreso del Estado de Sonora aprob\u00f3, con modificaciones, las leyes y presupuestos de ingresos de los ayuntamientos, con excepci\u00f3n de la correspondiente a Hermosillo, aunque s\u00ed autoriz\u00f3 a la capital el refinanciamiento de su deuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los diputados Norberto Barraza Almaz\u00e1n (PES), Emeterio Ochoa Baz\u00faa (PRI), David Figueroa Ortega (PVEM) y las diputadas Rebeca Irene Silva Gallardo (NAS) y Gabriela Danitza F\u00e9lix Boj\u00f3rquez (MC) presentaron el dictamen de la Comisi\u00f3n de Presupuestos y Asuntos Municipales, mediante el cual el Congreso aprob\u00f3, con modificaciones, las leyes y presupuestos de ingresos de los ayuntamientos para el ejercicio fiscal 2025, exceptuando al municipio de Hermosillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con este dictamen, el proceso de revisi\u00f3n incluy\u00f3 un an\u00e1lisis de fondo para eliminar disposiciones inconstitucionales, revisar los ingresos proyectados de cada ayuntamiento y evaluar las estrategias para mejorar la recaudaci\u00f3n y el uso de los recursos p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>RINDE PROTESTA ADRIEL C\u00d3RDOVA PIMENTEL<\/strong> <strong>COMO MAGISTRADO DEL STJ<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se nombr\u00f3, por unanimidad, a Adriel C\u00f3rdova Pimentel como magistrado del Supremo Tribunal de Justicia quien, adem\u00e1s, rindi\u00f3 protesta ante el Pleno de la actual legislatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Gabriela Danitza F\u00e9lix Boj\u00f3rquez (MC) destac\u00f3, en un posicionamiento, los retos que enfrentan las aduanas en el pa\u00eds. Asimismo, hizo un llamado a las autoridades competentes para revisar el estado de las aduanas en Sonora y garantizar su eficiencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CLAUSURAN PRIMER PRIODO ORDINARIO DE SESIONES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al desahogar el orden del d\u00eda, el diputado Omar Francisco Del Valle Colosio (PVEM), presidente de la mesa directiva, dio lectura al decreto de clausura del primer periodo de sesiones ordinarias del primer a\u00f1o de ejercicio constitucional de la 64\u00aa Legislatura. Posteriormente, los legisladores entonaron el Himno Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador inform\u00f3 que la clausura del periodo surte efectos a partir del 15 de diciembre. Asimismo, anunci\u00f3 que la mesa directiva de la Diputaci\u00f3n Permanente estar\u00e1 integrada por Omar Francisco Del Valle Colosio (PVEM), como presidente; Ros\u00e1ngela Amairany Pe\u00f1a Escalante (PES), como vicepresidenta; Mar\u00eda Eduwiges Espinoza Tapia (Morena), como secretaria; y como suplentes, Jes\u00fas Manuel Scott S\u00e1nchez (MC) y Rub\u00e9n Refugio Gonz\u00e1lez Aguayo (PT).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, se inform\u00f3 que el aviso de la Presidencia para la sesi\u00f3n de instalaci\u00f3n de la Diputaci\u00f3n Permanente, correspondiente al periodo del 15 de diciembre de 2024 al 31 de enero de 2025, ser\u00e1 publicado en la Gaceta Parlamentaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>-La propuesta del Ayuntamiento presenta irregularidades e incrementos desproporcionados en multas que afectar\u00e1n severamente a los hermosillenses -Hermosillo deber\u00e1 mantener la misma Ley de Ingresos 2024 para el pr\u00f3ximo a\u00f1o Hermosillo, Sonora; 15 de diciembre del 2024.- El Proyecto de Ley de Ingresos 2025, presentado por el Ayuntamiento de Hermosillo, fue rechazado por las bancadas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[119,8,115,105,9],"tags":[],"class_list":["post-21802","post","type-post","status-publish","format-standard","has-post-thumbnail","category-congreso","category-hermosillo","category-politica","category-principal","category-sonora"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21802"}],"version-history":[{"count":2,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21802\/revisions"}],"predecessor-version":[{"id":21819,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21802\/revisions\/21819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21803"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}