{"id":21735,"date":"2024-12-14T00:35:17","date_gmt":"2024-12-14T07:35:17","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21735"},"modified":"2024-12-14T00:35:19","modified_gmt":"2024-12-14T07:35:19","slug":"nunca-hubo-denuncia-formal-contra-el-comercio-chino-comerciantes-de-hermosillo","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/14\/nunca-hubo-denuncia-formal-contra-el-comercio-chino-comerciantes-de-hermosillo\/","title":{"rendered":"Nunca hubo denuncia formal contra el comercio Chino: Comerciantes de Hermosillo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>-Nuestra inconformidad fue medi\u00e1tica por la competencia desleal que representaban, asegur\u00f3 Rub\u00e9n L\u00f3pez Peralta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomado de Dossier Pol\u00edtico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santiago Garc\u00eda C.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viernes 13 de diciembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora.- Rub\u00e9n L\u00f3pez Peralta, Presidente de la Uni\u00f3n Comerciantes Hermosillo descart\u00f3 que el comercio organizado haya interpuesto alguna queja o denuncia formal ante la autoridad en contra de los negocios que comercializaban mercanc\u00eda China en Sonora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconoci\u00f3 que medi\u00e1ticamente liderazgos de las diferentes c\u00e1maras de comercio manifestaron su inconformidad p\u00fablicamente con el establecimiento de estos negocios, antes y despu\u00e9s de su apertura porque representaban una competencia desleal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros ten\u00edamos varios meses comentando el tema de estos comercios, se visualizaba que sus mercanc\u00edas no estaban ingresadas legalmente al pa\u00eds debido a los precios que estaban manejando, que incluso no cumplen con la norma oficial mexicana. Y esto se estaba traduciendo en p\u00e9rdida de ventas por la competencia desleal de este tipo de comercios a los comercios locales establecidos que s\u00ed cumplen con los lineamientos. Esta p\u00e9rdida de venta empez\u00f3 en un 10, luego el 15-20 por ciento y lleg\u00f3 hasta un 40 por ciento de los comercios locales afectados que cuentan con mercanc\u00edas afines a los de estos locales chinos\u201d, se\u00f1al\u00f3 en entrevista para Dossier Pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toda esta acci\u00f3n por parte del Gobierno Federal, de implementar este operativo denominado limpieza en todos los Estados de la Rep\u00fablica para combatir el comercio de mercanc\u00eda introducida al pa\u00eds de manera ilegal, se da despu\u00e9s de un operativo que se llev\u00f3 a cabo en la ciudad de M\u00e9xico donde se localiz\u00f3 mercanc\u00eda ilegal, acciones en las que los comerciantes de Sonora est\u00e1n totalmente de acuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros de alguna forma estamos a favor de este tipo de decomisos para que exista una competencia con suelo parejo y que termine de alguna forma beneficiando a quienes est\u00e9n realizando mejor su trabajo. Si ellos, comercio Chino, no est\u00e1n cumpliendo con la ley deben de tener alguna sanci\u00f3n y al momento de revisarlos salieron esas irregularidades y se les decomis\u00f3 la mercanc\u00eda la cual tienen la opci\u00f3n de recuperar presentando sus facturas, sus pedimentos y pagos de correspondientes de su legal ingreso al pa\u00eds\u201d, coment\u00f3 Leyva Peralta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manifest\u00f3 que si el Gobierno Federal ha tomado la iniciativa en el combate a la mercanc\u00eda ilegal, debe ir m\u00e1s all\u00e1 que solo los operativos que lleva a cabo, sino ampliar la investigaci\u00f3n para determinar c\u00f3mo y por d\u00f3nde est\u00e1 ingresando esta mercanc\u00eda al pa\u00eds, que no es poca, sino son grandes contenedores con miles de art\u00edculos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntraron por alg\u00fan Puerto, alguna de las fronteras que M\u00e9xico tiene para recibir, porque llegan en contenedores trasportados en grandes embarcaciones y hay todo un procedimiento que se debe de cumplir, ah\u00ed es donde la autoridad deber\u00e1 de revisar, pero eso ya le compete al gobierno federal porque ya es tema de aduana\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para finalizar, se\u00f1al\u00f3 que con estos operativos realizados se va a notar una recuperaci\u00f3n de los comercios que estaban siendo afectados y el compromiso que tiene el comercio local es respetar los precios de las mercanc\u00edas que tienen etiquetadas mientras que los consumidores, revisar precios en varios comercios antes de realizar una compra, que exijan sus tickets de compra para hacer v\u00e1lida la garant\u00eda para que el dinero con el que cuentan fruto de su trabajo, les rinda en estas fechas decembrinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/dossierpolitico.com\/2024\/12\/13\/nunca-hubo-denuncia-formal-contra-el-comercio-chino-nuestra-inconformidad-fue-mediatica-por-la-competencia-desleal-que-representaban-rlp\/\">https:\/\/dossierpolitico.com\/2024\/12\/13\/nunca-hubo-denuncia-formal-contra-el-comercio-chino-nuestra-inconformidad-fue-mediatica-por-la-competencia-desleal-que-representaban-rlp\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Nuestra inconformidad fue medi\u00e1tica por la competencia desleal que representaban, asegur\u00f3 Rub\u00e9n L\u00f3pez Peralta Tomado de Dossier Pol\u00edtico Santiago Garc\u00eda C. Viernes 13 de diciembre de 2024 Hermosillo, Sonora.- Rub\u00e9n L\u00f3pez Peralta, Presidente de la Uni\u00f3n Comerciantes Hermosillo descart\u00f3 que el comercio organizado haya interpuesto alguna queja o denuncia formal ante la autoridad en contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[8,115],"tags":[],"class_list":["post-21735","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hermosillo","category-politica"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21735"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21735\/revisions"}],"predecessor-version":[{"id":21737,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21735\/revisions\/21737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21736"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}