{"id":21698,"date":"2024-12-12T22:01:34","date_gmt":"2024-12-13T05:01:34","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21698"},"modified":"2024-12-12T22:01:36","modified_gmt":"2024-12-13T05:01:36","slug":"trasladan-a-genaro-garcia-luna-a-prision-de-oklahoma","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/12\/trasladan-a-genaro-garcia-luna-a-prision-de-oklahoma\/","title":{"rendered":"Trasladan a Genaro Garc\u00eda Luna a prisi\u00f3n de Oklahoma"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Fue sentenciado a 38 a\u00f1os de prisi\u00f3n por el juez de distrito estadunidense Brian Cogan, quien anunci\u00f3 la sentencia en el tribunal federal de Brooklyn.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomado de La Jornada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foto Jos\u00e9 Carlo Gonz\u00e1lez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jueves 12 de diciembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ex secretario de Seguridad P\u00fablica durante el sexenio de Felipe Calder\u00f3n Hinojosa (2006-2012), Genaro Garc\u00eda Luna, fue trasladado a una prisi\u00f3n federal en Oklahoma donde permanecer\u00e1 provisionalmente mientras se decide el lugar definitivo donde cumplir\u00e1 su condena, inform\u00f3 el Bur\u00f3 Federal de Prisiones de Estados Unidos (BOP, por sus siglas en ingl\u00e9s) en su sitio web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con n\u00famero de registro 59745-177, Garc\u00eda Luna permanec\u00eda en el Centro Metropolitano de Detenci\u00f3n de Brooklyn, Nueva York, donde enfrent\u00f3 su juicio y el pasado 16 de octubre fue sentenciado a 38 a\u00f1os de prisi\u00f3n por el juez de distrito estadunidense Brian Cogan, quien anunci\u00f3 la sentencia (https:\/\/www.jornada.com.mx\/2024\/10\/17\/politica\/003n1pol)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez recomend\u00f3 que el ex secretario fuera enviado definitivamente a una prisi\u00f3n cerca de Washington, ya que su familia vive en Virginia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una presentaci\u00f3n judicial del 19 de septiembre, los fiscales solicitaron cadena perpetua para Garc\u00eda Luna, de 56 a\u00f1os, despu\u00e9s de que fue declarado culpable en un juicio en febrero de 2023 por participar en una empresa delictiva de drogas, participar en varias conspiraciones y hacer declaraciones falsas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades informaron que Garc\u00eda Luna acept\u00f3 millones de d\u00f3lares en sobornos del c\u00e1rtel de Sinaloa, alguna vez liderado por Joaqu\u00edn Guzm\u00e1n Loera, mejor conocido como \u201cEl Chapo\u201d, y a cambio protegi\u00f3 a sus miembros del arresto y protegi\u00f3 sus env\u00edos de coca\u00edna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al anunciar la sentencia de 460 meses, Cogan dijo que Garc\u00eda Luna deber\u00eda tener &#8220;algo de luz al final del t\u00fanel&#8221;, y le atribuy\u00f3 el m\u00e9rito por su labor de ense\u00f1anza a otros reclusos en el Centro de Detenci\u00f3n Metropolitano de Brooklyn. Sin embargo, Cogan afirm\u00f3 que el ex fucnionaroo vivi\u00f3 una &#8220;doble vida&#8221;, en la que el da\u00f1o que caus\u00f3 superaba a sus buenas acciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Aparte de tu comportamiento muy agradable y tu elocuencia, tienes el mismo tipo de matonismo que El Chapo, s\u00f3lo que se manifiesta de manera diferente&#8221;, sentenci\u00f3 Cogan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con informaci\u00f3n de Reuters<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.jornada.com.mx\/noticia\/2024\/12\/12\/mundo\/trasladan-a-garcia-luna-a-prision-de-oklahoma-1915\">https:\/\/www.jornada.com.mx\/noticia\/2024\/12\/12\/mundo\/trasladan-a-garcia-luna-a-prision-de-oklahoma-1915<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue sentenciado a 38 a\u00f1os de prisi\u00f3n por el juez de distrito estadunidense Brian Cogan, quien anunci\u00f3 la sentencia en el tribunal federal de Brooklyn. Tomado de La Jornada Redacci\u00f3n Foto Jos\u00e9 Carlo Gonz\u00e1lez Jueves 12 de diciembre de 2024 El ex secretario de Seguridad P\u00fablica durante el sexenio de Felipe Calder\u00f3n Hinojosa (2006-2012), Genaro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,113],"tags":[],"class_list":["post-21698","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mexico","category-seguridad"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21698"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21698\/revisions"}],"predecessor-version":[{"id":21700,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21698\/revisions\/21700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21699"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}