{"id":21686,"date":"2024-12-12T21:38:49","date_gmt":"2024-12-13T04:38:49","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21686"},"modified":"2024-12-12T21:38:52","modified_gmt":"2024-12-13T04:38:52","slug":"pragmatico-polemico-e-intimo-de-bukele-el-rastro-salvadoreno-de-ronald-johnson-el-hombre-de-trump-para-mexico","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/12\/pragmatico-polemico-e-intimo-de-bukele-el-rastro-salvadoreno-de-ronald-johnson-el-hombre-de-trump-para-mexico\/","title":{"rendered":"Pragm\u00e1tico, pol\u00e9mico e \u00edntimo de Bukele: el rastro salvadore\u00f1o de Ronald Johnson, el hombre de Trump para M\u00e9xico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>-El coronel retirado estuvo menos de dos a\u00f1os como embajador en el pa\u00eds, pero le bast\u00f3 para volverse un amigo personal del presidente. En los ochenta, lider\u00f3 operaciones de combate y contrainsurgencia durante la guerra civil<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomado de El Pa\u00eds<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El\u00edas Camhaji y Bryan Avelar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jueves 12 de diciembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nayib Bukele ten\u00eda sentimientos encontrados. Posaba sonriente para las fotos oficiales, pero reconoc\u00eda en su discurso que estaba triste y lleno de nostalgia. \u201cSe va un gran amigo\u201d, declar\u00f3 el mandatario salvadore\u00f1o el 18 de enero de 2021, en la ceremonia de despedida que organiz\u00f3 para Ronald Johnson, el embajador estadounidense. Dos d\u00edas antes de que hiciera sus maletas, Bukele entreg\u00f3 al diplom\u00e1tico la Orden Nacional Jos\u00e9 Mat\u00edas Delgado, en el grado de Gran Cruz Placa de Plata, una de las condecoraciones m\u00e1s altas del pa\u00eds centroamericano. En ese mismo acto, Johnson se convirti\u00f3 en la primera persona en recibir la Gran Orden Francisco Moraz\u00e1n, una insignia creada ex profeso para distinguir su breve estancia de menos de dos a\u00f1os. \u201cDespu\u00e9s de casi 50 a\u00f1os de servicio al Gobierno, puedo decir que este ha sido el mayor honor de mi vida profesional\u201d, agradeci\u00f3 conmovido y colmado de elogios. Casi cuatro a\u00f1os m\u00e1s tarde, Donald Trump ha vuelto apostar por el coronel en retiro, ex boina verde y veterano de la CIA con una nueva misi\u00f3n: ser su hombre en M\u00e9xico, la primera l\u00ednea de los intereses de Estados Unidos en Am\u00e9rica Latina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDistinguido pueblo, mi nombre es Ronald Johnson y soy el nuevo embajador de Estados Unidos en El Salvador\u201d. As\u00ed se presentaba el exmilitar, en espa\u00f1ol y con marcado acento estadounidense, en un video grabado en septiembre de 2019, a un par de d\u00edas de su desembarco. Bukele acababa de llegar al poder tres meses antes y Trump quer\u00eda un soldado que pusiera a raya a las maras, principalmente a la MS-13 y Barrio 18, y controlara el \u00e9xodo de migrantes a Estados Unidos. El presidente se hab\u00eda referido en 2018 al pa\u00eds centroamericano como \u201cun agujero de mierda\u201d \u2015aunque despu\u00e9s lo neg\u00f3\u2015, pero estaba preocupado por ciertos coqueteos que su hom\u00f3logo salvadore\u00f1o hab\u00eda tenido con China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque Johnson no ten\u00eda experiencia como embajador, s\u00ed ten\u00eda a cuestas m\u00e1s de una d\u00e9cada en las Fuerzas Armadas y otros 20 a\u00f1os en Inteligencia, y Trump quer\u00eda que fuera sus ojos y sus o\u00eddos en el arranque de la nueva Administraci\u00f3n. El diplom\u00e1tico se lanz\u00f3 al cortejo del nuevo mandatario de inmediato. \u201cMis prioridades son las mismas que las del presidente Bukele en su Administraci\u00f3n, es el momento de un cambio para m\u00e1s seguridad, m\u00e1s prosperidad y m\u00e1s oportunidades para todos\u201d, afirm\u00f3 en su primer mensaje a los salvadore\u00f1os. \u201cNuestras prioridades son las mismas y por eso lograremos grandes cosas juntos\u201d, refrend\u00f3 Bukele en Twitter, para dejar claro que se iba a alinear. \u201cEst\u00e1 tratando con un Gobierno que no expresa amistad, sino m\u00e1s bien sumisi\u00f3n\u201d, sentenciaba Rub\u00e9n Zamora, exembajador salvadore\u00f1o en Washington, en una columna publicada en El Faro en 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No era la primera vez que Johnson pisaba El Salvador. En su paso por el Ej\u00e9rcito estadounidense, lider\u00f3 operaciones de combate durante la guerra civil y era uno de 55 asesores que trazaron la estrategia contra la insurgencia en los ochenta, de acuerdo con su biograf\u00eda militar. Zamora rese\u00f1aba a su llegada lo poco com\u00fan que era la designaci\u00f3n de un boina verde como embajador en la historia diplom\u00e1tica entre ambos pa\u00edses. \u201cDurante los \u00faltimos 60 a\u00f1os, m\u00e1s del 80% de los embajadores de Estados Unidos enviados a nuestro pa\u00eds han sido diplom\u00e1ticos de carrera. Johnson es el \u00fanico proveniente del Ej\u00e9rcito y la CIA\u201d, se\u00f1alaba, un hecho que tambi\u00e9n fue destacado en M\u00e9xico esta semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ronald D. Johnson<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPrevio a su llegada, la relaci\u00f3n bilateral hab\u00eda sido muy tensa, hubo un enfriamiento\u201d, rese\u00f1a el salvadore\u00f1o \u00d3scar Chac\u00f3n, portavoz de Alianza Am\u00e9ricas, una red de organizaciones de migrantes en Estados Unidos. Su predecesora, Jean Manes, hab\u00eda tenido varias fricciones en el frente pol\u00edtico, al tener diferencias bastante p\u00fablicas con el izquierdista Frente Farabundo Mart\u00ed para la Liberaci\u00f3n Nacional (FMLN). \u201cJohnson, en cambio, es un hombre sumamente pragm\u00e1tico, fue una de las razones principales detr\u00e1s de su nombramiento\u201d, afirma el especialista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chac\u00f3n asegura que la instrucci\u00f3n principal que recibi\u00f3 el embajador fue reparar esa fractura y asegurar el alineamiento de El Salvador, al ser uno de los pa\u00edses con los mayores flujos migratorios. \u201cYo veo a Johnson como a una persona que vino a decir \u2018miren, yo vengo a restaurar la costumbre de siempre de los embajadores estadounidenses, si te alineas con mis intereses y prioridades, te voy a dar el respaldo que necesitas y eso incluye participar en todas las actividades sociales donde me necesites\u201d, comenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bukele entendi\u00f3 el mensaje. Poco despu\u00e9s de la llegada de Johnson, el Gobierno salvadore\u00f1o anunci\u00f3 la creaci\u00f3n de una nueva patrulla fronteriza, una versi\u00f3n tropicalizada de la Border Patrol estadounidense que se encargar\u00eda exclusivamente de combatir el flujo ilegal de migrantes. Las autoridades firmaron tambi\u00e9n el Acuerdo de Cooperaci\u00f3n de Asilo (ACA), que permit\u00eda que los migrantes salvadore\u00f1os que pidieran asilo pudieran ser deportados de nuevo a su pa\u00eds para hacer la solicitud desde ah\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Johnson pronto se convirti\u00f3 en un aliado cr\u00edtico para su Gobierno y como tal, en una figura pr\u00e1cticamente omnipresente en ruedas de prensa, reuniones de trabajo e, incluso, actividades privadas. \u201cCon Estados Unidos tenemos una alianza\u201d, dijo el presidente unos d\u00edas despu\u00e9s del nombramiento del diplom\u00e1tico en 2019. \u201cPero creo que con el embajador Johnson y su esposa, Alina, tendremos una amistad personal\u201d, coment\u00f3 en tono prof\u00e9tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el terreno oficial, el embajador se gan\u00f3 la confianza, espaldarazo tras espaldarazo, alabando las pol\u00edticas de las nuevas autoridades salvadore\u00f1as anteriores al llamado R\u00e9gimen de Excepci\u00f3n. Aplaudi\u00f3 el arresto y la extradici\u00f3n de pandilleros, la reducci\u00f3n de los \u00edndices delictivos y la estrategia contra el crimen organizado. Asegur\u00f3 que la migraci\u00f3n hab\u00eda ca\u00eddo \u201cun 81%\u201d en 2020, sin hacer \u00e9nfasis en la pandemia ni en uno de los reg\u00edmenes de confinamiento m\u00e1s duros del mundo, y aunque especialistas como Chac\u00f3n tachan el dato de \u201cantojadizo\u201d. Ante las preocupaciones internacionales por la situaci\u00f3n de los derechos humanos, decidi\u00f3 mirar hacia otro lado y abog\u00f3 por que El Salvador fuera certificado como un pa\u00eds \u201cque respeta las libertades\u201d para que siguiera recibiendo fondos de asistencia de Washington. \u201cLa relaci\u00f3n se ha revitalizado\u201d, celebr\u00f3 en un art\u00edculo de opini\u00f3n, publicado a un a\u00f1o de tomar el cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEra muy medi\u00e1tico y cada vez que Johnson abr\u00eda la boca era para apoyar a Bukele, pero adem\u00e1s sub\u00eda fotograf\u00edas con \u00e9l o permit\u00eda que subiera im\u00e1genes a sus redes en situaciones poco comunes para un embajador: comiendo langosta o paseando en lancha\u201d, afirma \u00d3scar Mart\u00ednez, jefe de redacci\u00f3n de El Faro. Bukele tambi\u00e9n hizo p\u00fablica la importancia de su amistad con el embajador. Previo a la Nochebuena de 2019, el mandatario public\u00f3 una fotograf\u00eda junto al diplom\u00e1tico comiendo langostas en un restaurante en Miami y luego, en enero de 2020, public\u00f3 otra foto de las dos familias de paseo por el estero de Jaltepeque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su buena amistad sirvi\u00f3 para que el embajador solapara muchos comportamientos cuestionables y autoritarios del mandatario salvadore\u00f1o. En una ocasi\u00f3n, cuatro meses despu\u00e9s de que Bukele tomara el Congreso usando militares fuertemente armados con la excusa de aprobar un pr\u00e9stamo para reforzar sus planes de seguridad, Johnson no solo evit\u00f3 hablar del tema, sino que hizo una finta hablando sobre la amistad de ambos. \u201cTodo mundo me pregunta por nuestra amistad, el presidente Bukele y su familia son mis amigos. No estamos de acuerdo en todo, pero si tiene un amigo que est\u00e1 de acuerdo con usted en todo, necesita encontrarse un nuevo amigo\u201d, dijo Johnson.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mart\u00ednez comenta que el acercamiento se dio cuando El Faro y otros medios sacaron a la luz el pol\u00e9mico pacto de Bukele con las pandillas. Mientras el presidente negaba que existiera, el embajador declaraba que lo importante era que bajara el crimen. El periodista afirma que la afinidad entre ambos eran obvia, incluso en sus estilos. \u201cJohnson quer\u00eda proyectar la imagen de que era un hombre fuerte, de un exagente de la CIA, de alguien que sub\u00eda fotos montando motos en sus vacaciones\u201d, recuerda. \u201cY a Bukele le encanta fotografiarse rodeado de militares, con este sincretismo de mezclar a los soldados y a Dios, en eso se parec\u00edan mucho\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el idilio dur\u00f3 poco. Diecis\u00e9is meses despu\u00e9s de que Johnson asumiera el cargo, Joe Biden lleg\u00f3 al poder, reinstal\u00f3 a Manes en la embajada y las concesiones a Bukele se acabaron. En 2021, Washington incluy\u00f3 a 13 funcionarios salvadore\u00f1os en la Lista Engel, que expone a servidores ligados a pr\u00e1cticas corruptas, entre ellos varios socios del presidente, como magistrados del Tribunal Supremo Electoral y exministros de su Gabinete. En un punto \u00e1lgido de las tensiones, Johnson le mand\u00f3 un mensaje grabado de felicitaci\u00f3n al mandatario y a su familia para Navidad. \u201cTiempos aquellos cuando los embajadores eran enviados para fortalecer las relaciones entre las naciones\u201d, dijo para agradecerle y lanzar una pulla a su sucesora. Manes, ahora como encargada de negocios, dej\u00f3 El Salvador en noviembre de ese a\u00f1o. \u201cNo tienen inter\u00e9s de mejorar la relaci\u00f3n\u201d, reproch\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cJuntos, vamos a poner fin a los cr\u00edmenes de los migrantes, detener los flujos ilegales de fentanilo y otras drogas peligrosas a nuestro pa\u00eds, y hacer a Estados Unidos seguro otra vez\u201d, se\u00f1al\u00f3 Trump al anunciar a Johnson, que a\u00fan debe ser ratificado por el Senado antes de llegar a M\u00e9xico el pr\u00f3ximo a\u00f1o. Mucho se ha hablado de su experiencia en Seguridad y en Inteligencia, incluso en el combate al narcotr\u00e1fico y al terrorismo, pero Chac\u00f3n se\u00f1ala que hay otras lecciones que M\u00e9xico puede sacar de su paso por El Salvador. \u201cEl pragmatismo es un elemento de primera l\u00ednea de su perfil y es algo que a M\u00e9xico deber\u00eda tener en cuenta\u201d, afirma. \u201cSu pragmatismo no se amarra a paradigmas ideol\u00f3gicos, incluso aunque crea en ellos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/elpais.com\/mexico\/2024-12-12\/pragmatico-polemico-e-intimo-de-bukele-el-rastro-salvadoreno-de-ronald-johnson-el-hombre-de-trump-para-mexico.html\">https:\/\/elpais.com\/mexico\/2024-12-12\/pragmatico-polemico-e-intimo-de-bukele-el-rastro-salvadoreno-de-ronald-johnson-el-hombre-de-trump-para-mexico.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-El coronel retirado estuvo menos de dos a\u00f1os como embajador en el pa\u00eds, pero le bast\u00f3 para volverse un amigo personal del presidente. En los ochenta, lider\u00f3 operaciones de combate y contrainsurgencia durante la guerra civil Tomado de El Pa\u00eds El\u00edas Camhaji y Bryan Avelar Jueves 12 de diciembre de 2024 Nayib Bukele ten\u00eda sentimientos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[7,115],"tags":[],"class_list":["post-21686","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional","category-politica"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21686"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21686\/revisions"}],"predecessor-version":[{"id":21688,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21686\/revisions\/21688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21687"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}