{"id":21652,"date":"2024-12-12T00:05:06","date_gmt":"2024-12-12T07:05:06","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21652"},"modified":"2024-12-12T00:05:09","modified_gmt":"2024-12-12T07:05:09","slug":"sheinbaum-en-sonora-agenda-llena-de-retos","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/12\/sheinbaum-en-sonora-agenda-llena-de-retos\/","title":{"rendered":"Sheinbaum en Sonora: agenda llena de retos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Columna El Zancudo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arturo Soto Mungu\u00eda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sheinbaum en Sonora: agenda llena de retos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jueves 12 de diciembre de 2924<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se ha revelado a\u00fan la agenda que vendr\u00e1 a cubrir Claudia Sheinbaum a Sonora en su primera visita ya como presidenta en funciones, el pr\u00f3ximo 21 de diciembre, en el marco de una gira por los estados del norte del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La informaci\u00f3n oficial dice que el gobernador Alfonso Durazo y el equipo de la mandataria trabajan en ello, pero no es muy aventurado suponer que hay algunos temas urgentes sobre los que en Sonora se esperan definiciones ejecutivas de gran calado, habida cuenta el horizonte en el que aparecen no pocos nubarrones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El pr\u00f3ximo 20 de enero asume la presidencia de Estados Unidos Donald Trump, quien ha adelantado virajes en sus pol\u00edticas respecto a nuestro pa\u00eds, particularmente en el tema de la deportaci\u00f3n masiva de migrantes y el combate al crimen organizado, particularmente aquellas bandas que producen y\/o trafican fentanilo hacia el pa\u00eds vecino, donde mueren alrededor de cien mil personas al a\u00f1o por el uso de esa sustancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La visita de la presidenta a los estados del norte mexicano podr\u00eda entenderse en ese contexto. Desde Baja California hasta Tamaulipas, pasando por Chihuahua, Nuevo Le\u00f3n y Coahuila deber\u00e1n estar preparados para enfrentar los efectos de una ola de deportaciones como no se hab\u00eda visto ni siquiera en el gobierno de Barak Obama, que seg\u00fan registros expuls\u00f3 de su pa\u00eds casi tres millones de indocumentados durante los ocho a\u00f1os de su gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Trump ha amenazado con subir esa cifra hasta 11 millones en esta su segunda gesti\u00f3n, aunque eso tambi\u00e9n lo dijo antes de asumir la primera, y en realidad se qued\u00f3 muy por debajo de esa cifra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Como sea, es la hora de preguntarse si en Sonora y especialmente en sus ciudades fronterizas se cuenta con suficientes recursos humanos, materiales, log\u00edsticos, de infraestructura y equipamiento para atender esa nueva realidad que plantean los pr\u00f3ximos cuatro a\u00f1os, al menos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Claramente, lo que hasta ahora hemos visto en ciudades y carreteras de Sonora en materia de migraci\u00f3n no parece acercarse siquiera al escenario que plantea la deportaci\u00f3n de miles, decenas de miles de indocumentados no solo mexicanos, sino de Centro y Sudam\u00e9rica, del caribe, \u00c1frica y Asia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El fen\u00f3meno es de doble v\u00eda, pues mientras EEUU enviar\u00e1 un considerable flujo de migrantes a M\u00e9xico, la migraci\u00f3n que viene de sur a norte, como indican experiencias previas, no cesar\u00e1. El gobierno federal mexicano y los estados fronterizos tendr\u00e1n que poner sus mejores empe\u00f1os para atender esa nueva realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El tema no es sencillo porque adem\u00e1s de los muchos recursos econ\u00f3micos que se necesitan -y que EEUU no est\u00e1 dispuesto a proporcionar de alg\u00fan modo- se requieren abordajes multidisciplinarios e interinstitucionales no del todo vistos hasta hoy por parte del gobierno mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El otro tema caliente es el de la seguridad p\u00fablica, se\u00f1aladamente el que involucra el accionar de bandas del crimen organizado que, en el caso de los estados fronterizos adquiere para Estados Unidos un car\u00e1cter de seguridad nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En Sonora, y supongo que en otros estados tambi\u00e9n, ya hay una larga tradici\u00f3n de colaboraci\u00f3n con agencias de seguridad estadunidenses y entre las fuerzas armadas de ambos pa\u00edses, pero el nuevo enfoque que pretende darle Donald Trump apelando al principio de extraterritorialidad implica nuevos retos en la relaci\u00f3n bilateral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Esos son temas coyunturales que plantea la sucesi\u00f3n en EEUU, pero hay otros digamos m\u00e1s dom\u00e9sticos aunque no menos serios, que el gobierno de Claudia Sheinbaum debe abordar con el estatal. Por ejemplo los dilemas que enfrenta la producci\u00f3n agropecuaria sobre todo en el sur del estado, donde la falta de lluvias ya dej\u00f3 cientos de miles de hect\u00e1reas sin sembrar, lo que est\u00e1 generando un clima de zozobra entre los productores de los valles del Yaqui y el Mayo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Sheinbaum no es ajena a esta problem\u00e1tica. Como presidenta electa, acompa\u00f1\u00f3 al entonces presidente en funciones, Andr\u00e9s Manuel L\u00f3pez Obrador en sus giras por Sonora; estuvo en El Desemboque con los seris, en Puerto Pe\u00f1asco, en Guaymas y en V\u00edcam, coraz\u00f3n del territorio yaqui. Conoce muy bien los motivos y proyecciones de los planes de justicia para las etnias a los que se comprometi\u00f3 a dar continuidad, lo mismo que a los proyectos de modernizaci\u00f3n del puerto de Guaymas, la carretera Guaymas-Chihuahua y la reubicaci\u00f3n de las v\u00edas del ferrocarril para sacarlas del casco urbano de Nogales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Toda visita presidencial despierta siempre grandes expectativas por los anuncios que suelen hacerse en estas giras. La del pr\u00f3ximo 21 de diciembre no es la excepci\u00f3n. Se advierte que hay una excelente relaci\u00f3n de la presidenta con el gobernador pero tambi\u00e9n se advierten temas que exigen respuestas a las que hay que estar muy atentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<strong>II<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Desde hace tiempo se viene escuchando en Radio Pasillo la versi\u00f3n de que Alejandro L\u00f3pez Caballero ya levant\u00f3 la mano para buscar la candidatura del PAN a la alcald\u00eda de Hermosillo, cargo que ya ocup\u00f3 en el trienio 2012-2015, despu\u00e9s de haberse desempe\u00f1ado los tres a\u00f1os anteriores como secretario de Hacienda del gobernador Guillermo Padr\u00e9s El\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;De confirmarse esta versi\u00f3n, esta jugada mover\u00eda muchas piezas en el tablero pol\u00edtico de la capital del estado, acaso el \u00fanico enclave importante, el \u00faltimo reducto de la oposici\u00f3n, la plaza m\u00e1s grande de Sonora donde Morena es oposici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Una plaza, hay que decirlo, que la alianza PRI-PAN-PRD gan\u00f3 en 2021 arrebat\u00e1ndosela a Morena, que no pudo conservarla llevando a C\u00e9lida L\u00f3pez como candidata a la reelecci\u00f3n. Esa misma alianza refrend\u00f3 el triunfo en 2024 pero en ambos procesos tuvo mucho que ver el candidato: Antonio Astiazar\u00e1n Guti\u00e9rrez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Quit\u00e1ndole a esa alianza la figura del alcalde de Hermosillo, la caballada se advierte sumamente flaca, por no decir fam\u00e9lica. Alejandro L\u00f3pez Caballero ser\u00eda una figura fuerte, conocida, pol\u00e9mica y con mucho dinero, pero llena de claroscuros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Ayer, el colega y amigo Gustavo Valenzuela solt\u00f3 la versi\u00f3n de que este s\u00e1bado, L\u00f3pez Caballero se reunir\u00eda en la finca del exgobernador Guillermo Padr\u00e9s con personajes que lo acompa\u00f1aron en su fugaz y vilipendiado sexenio, para comenzar a trabajar en esa candidatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En los \u00faltimos dos procesos, Morena ha probado que en Hermosillo es una fuerza real y competitiva, que se ha quedado muy cerca del triunfo. Ya sin el To\u00f1o Astiazar\u00e1n y con muchas dudas sobre la eventualidad de mantener la alianza PRI-PAN el escenario para estas fuerzas luce m\u00e1s complicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El padrecismo, lejos de constituir una fortaleza para la candidatura de L\u00f3pez Caballero pareciera m\u00e1s bien una debilidad. Sus principales cuadros no son, que digamos, un dechado de popularidad; siguen teniendo peso en el PAN, pero ese partido no pasa por su mejor momento. De hecho, en el desangelado proceso de reelecci\u00f3n de Gildardo Real como dirigente estatal, se evidenci\u00f3 la grieta que se abri\u00f3 precisamente al final de la administraci\u00f3n de L\u00f3pez Caballero, cuando Dami\u00e1n Zepeda, el candidato del PAN a la alcald\u00eda rompi\u00f3 lanzas con quienes mandaban en ese momento en el partido y en el gobierno estatal, acus\u00e1ndolos de haberle dado la espalda y abrirle el camino a Manuel Ignacio Acosta, el candidato del PRI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Como alcalde, L\u00f3pez Caballero recibi\u00f3 primero al \u2018Maloro\u2019 que a Dami\u00e1n y ah\u00ed se comenz\u00f3 a escribir la historia de la recuperaci\u00f3n de la alcald\u00eda para el PRI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Antes que una figura de unidad, Alejandro L\u00f3pez Caballero reabrir\u00eda las heridas de aquel proceso y podr\u00eda ser un factor de divisi\u00f3n entre los blanquiazules. Pero de que generar\u00eda pol\u00e9mica, es un hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;Tambi\u00e9n me puedes seguir en X: @Chaposoto<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Visita www.elzancudo.com.mx<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Columna El Zancudo Arturo Soto Mungu\u00eda Sheinbaum en Sonora: agenda llena de retos Jueves 12 de diciembre de 2924 No se ha revelado a\u00fan la agenda que vendr\u00e1 a cubrir Claudia Sheinbaum a Sonora en su primera visita ya como presidenta en funciones, el pr\u00f3ximo 21 de diciembre, en el marco de una gira por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[125],"tags":[],"class_list":["post-21652","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arturo-soto-munguia"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21652"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21652\/revisions"}],"predecessor-version":[{"id":21654,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21652\/revisions\/21654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21653"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}