{"id":21631,"date":"2024-12-11T22:59:01","date_gmt":"2024-12-12T05:59:01","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21631"},"modified":"2024-12-11T22:59:04","modified_gmt":"2024-12-12T05:59:04","slug":"amenazan-empleados-del-pjf-en-sonora-con-nuevas-medidas-de-protesta","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/11\/amenazan-empleados-del-pjf-en-sonora-con-nuevas-medidas-de-protesta\/","title":{"rendered":"Amenazan empleados del PJF en Sonora con nuevas medidas de protesta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Manifestaron su rechazo al recorte de $15 mil millones de pesos anunciado en el presupuesto federal.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomado de Radio Formula Sonora<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antonio L\u00f3pez M.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi\u00e9rcoles 11 de diciembre<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trabajadores del Poder Judicial de la Federaci\u00f3n en Sonora (PJF) advirtieron de nuevas medidas de protesta, ante el inminente recorte que sufrir\u00e1 el organismo con el presupuesto del 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rafael Alejandro Flores, vocero de los empleados afectados, se\u00f1al\u00f3 que pudieran incurrir nuevamente en paralizaci\u00f3n de actividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHacemos un llamado y concientizamos a la sociedad, evidentemente tomaremos acciones, como puede ser otra vez la reducci\u00f3n de labores, u otras cuestiones que estar\u00e1n en la agenda, este d\u00eda veremos c\u00f3mo se resuelve en la C\u00e1mara de Diputados\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Flores indic\u00f3 que el recorte se espera que sea por el orden de los $15 mil millones de pesos, lo cual derivar\u00e1 en desaparici\u00f3n de plazas y juzgados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.radioformula.com.mx\/sonora\/2024\/12\/11\/amenazan-empleados-del-pjf-en-sonora-con-nuevas-medidas-de-protesta-844514.html\">https:\/\/www.radioformula.com.mx\/sonora\/2024\/12\/11\/amenazan-empleados-del-pjf-en-sonora-con-nuevas-medidas-de-protesta-844514.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manifestaron su rechazo al recorte de $15 mil millones de pesos anunciado en el presupuesto federal. Tomado de Radio Formula Sonora Antonio L\u00f3pez M. Mi\u00e9rcoles 11 de diciembre Trabajadores del Poder Judicial de la Federaci\u00f3n en Sonora (PJF) advirtieron de nuevas medidas de protesta, ante el inminente recorte que sufrir\u00e1 el organismo con el presupuesto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[115,105,9],"tags":[],"class_list":["post-21631","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-principal","category-sonora"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21631"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21631\/revisions"}],"predecessor-version":[{"id":21633,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21631\/revisions\/21633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21632"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}