{"id":21560,"date":"2024-12-10T23:02:07","date_gmt":"2024-12-11T06:02:07","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21560"},"modified":"2024-12-10T23:02:10","modified_gmt":"2024-12-11T06:02:10","slug":"el-cartel-de-sinaloa-esta-siendo-desmantelado-afirma-embajador-de-eu","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/10\/el-cartel-de-sinaloa-esta-siendo-desmantelado-afirma-embajador-de-eu\/","title":{"rendered":"El C\u00e1rtel de Sinaloa est\u00e1 siendo \u201cdesmantelado\u201d, afirma embajador de EU"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tomado de Aristegui Noticias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n AN \/ LP<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martes 10 de diciembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El embajador de Estados Unidos en M\u00e9xico, Ken Salazar, afirm\u00f3 este martes que el C\u00e1rtel de Sinaloa est\u00e1 siendo \u201cdesmantelado\u201d gracias a la colaboraci\u00f3n entre ambos pa\u00edses, y dijo ver con \u201coptimismo\u201d la estrategia de seguridad impulsada por la presidenta Claudia Sheinbaum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencia de prensa tras reunirse con empresarios, Salazar destac\u00f3 que es fundamental tener un \u201centendimiento claro entre Estados Unidos y M\u00e9xico porque desde los tiempos antes de llegar el presidente (Andr\u00e9s Manuel) L\u00f3pez Obrador se descompuso la relaci\u00f3n en t\u00e9rminos de seguridad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros hemos hecho bastante en crear una relaci\u00f3n nueva, por eso los carteles, por ejemplo, de Sinaloa, pues se est\u00e1 desmantelando\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salazar indic\u00f3, en este sentido, ve \u201ccon optimismo que la seguridad va a llegar a mejor lugar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cY eso le doy el cr\u00e9dito al gobierno de M\u00e9xico, porque son los marinos (Secretar\u00eda de Marina), los de Sedena (Secretar\u00eda de la Defensa Nacional), los de Guardia Nacional, y nosotros en apoyo, pero siempre con respeto a la soberan\u00eda de M\u00e9xico\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La captura de Ismael \u2018El Mayo\u2019 Zambada y de Joaqu\u00edn Guzm\u00e1n L\u00f3pez, uno de los hijos de \u2018El Chapo\u2019 Guzm\u00e1n, por autoridades de Estados Unidos en un operativo en Texas a finales de julio, ha provocado tensiones entre los pa\u00edses y un recrudecimiento de la violencia en la entidad que no ha cesado desde entonces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salazar detall\u00f3 que desde la embajada \u201ctrabajan y dan ideas a la presidenta\u201d por medio del canciller Juan Ram\u00f3n De la Fuente, y el Secretario de Seguridad y Protecci\u00f3n Ciudadana (SSPC), Omar Garc\u00eda Harfuch.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dijo ver con buenos ojos lo que el Gobierno \u201cest\u00e1 haciendo en Sinaloa y otros lugares\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace una semana, la SSPC inform\u00f3 sobre un operativo realizado en Sinaloa, estado del noroeste del pa\u00eds, en el que confiscaron cerca de 300 kilos de fentanilo en un domicilio y otros 800 kilos de la misma droga en una camioneta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta Sheinbaum ha destacado que es la incautaci\u00f3n \u201cm\u00e1s grande que se haya hecho\u201d de pastillas de fentanilo, equivalentes a m\u00e1s de 20 millones de dosis, lo que podr\u00eda haber generado cerca de 8,.000 millones de pesos (unos 400 millones de d\u00f3lares) en el mercado negro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, Salazar destac\u00f3 que cuando Sheinbaum fue jefa de Gobierno de la Ciudad de M\u00e9xico, \u201cinvirti\u00f3 arriba de 13 % de su presupuesto en la seguridad\u201d, lo que recomend\u00f3 hacer tambi\u00e9n a nivel nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces, veo con optimismo que la seguridad va a llegar a mejor lugar\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las declaraciones de Salazar ocurren en medio de la presi\u00f3n del presidente electo de Estados Unidos, Donald Trump, para que M\u00e9xico controle el tr\u00e1fico de fentanilo y la migraci\u00f3n, bajo amenaza de imponer aranceles del 25% a productos mexicanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/aristeguinoticias.com\/1012\/mexico\/el-cartel-de-sinaloa-esta-siendo-desmantelado-afirma-embajador-de-eu\">https:\/\/aristeguinoticias.com\/1012\/mexico\/el-cartel-de-sinaloa-esta-siendo-desmantelado-afirma-embajador-de-eu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tomado de Aristegui Noticias Redacci\u00f3n AN \/ LP Martes 10 de diciembre de 2024 El embajador de Estados Unidos en M\u00e9xico, Ken Salazar, afirm\u00f3 este martes que el C\u00e1rtel de Sinaloa est\u00e1 siendo \u201cdesmantelado\u201d gracias a la colaboraci\u00f3n entre ambos pa\u00edses, y dijo ver con \u201coptimismo\u201d la estrategia de seguridad impulsada por la presidenta Claudia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[7,115],"tags":[],"class_list":["post-21560","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional","category-politica"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21560"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21560\/revisions"}],"predecessor-version":[{"id":21562,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21560\/revisions\/21562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21561"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}