{"id":21527,"date":"2024-12-10T09:45:18","date_gmt":"2024-12-10T16:45:18","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21527"},"modified":"2024-12-10T09:45:21","modified_gmt":"2024-12-10T16:45:21","slug":"martin-borrego-renuncia-tras-escandalo-por-boda-en-el-munal","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/10\/martin-borrego-renuncia-tras-escandalo-por-boda-en-el-munal\/","title":{"rendered":"Mart\u00edn Borrego renuncia tras esc\u00e1ndalo por boda en el Munal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El exfuncionario utiliz\u00f3 su cargo en la Canciller\u00eda para pedir el espacio en el Munal y organizar el presunto aniversario 89 de las relaciones diplom\u00e1ticas entre M\u00e9xico y Rumania, el cual era en realidad en la celebraci\u00f3n de su matrimonio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomado de Proceso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redacci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martes 10 de diciembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CIUDAD DE M\u00c9XICO (apro).-Horas despu\u00e9s que la Canciller\u00eda diera a conocer el inicio de una investigaci\u00f3n por el presunto mal uso de su cargo p\u00fablico en la \u00e9poca en que era jefe de asesores en la dependencia, Mart\u00edn Borrego Llorente present\u00f3 su renuncia a Alicia B\u00e1rcena Ibarra, la titular de la Secretar\u00eda de Medio Ambiente y Recursos Naturales (Semarnar), donde fung\u00eda como coordinador de Contacto con la Ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una carta que hizo p\u00fablica, el funcionario admiti\u00f3 que fue &#8220;impropio&#8221; solicitar un espacio en el Museo Nacional de Arte (Munal) para celebrar un evento &#8220;privado&#8221;&#8211;su boda, seg\u00fan el columnista Claudio Ochoa&#8211;, y present\u00f3 a B\u00e1rcena sus disculpas por &#8220;haber faltado a su confianza&#8221; y por involucrarla en este &#8220;episodio&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la columna que public\u00f3 el pasado domingo en El Universal, Ochoa revel\u00f3 que Borrego utiliz\u00f3 su cargo en la Canciller\u00eda para pedir el espacio en el Munal y organizar el presunto aniversario 89 de las relaciones diplom\u00e1ticas entre M\u00e9xico y Rumania, el cual era en realidad en la celebraci\u00f3n de su matrimonio con su pareja de nacionalidad rumana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Ochoa, la propia B\u00e1rcena, entonces titular de la Secretar\u00eda de Relaciones Exteriores (SRE), asisti\u00f3 al evento, junto con otros altos funcionarios de la dependencia. La Canciller\u00eda inform\u00f3 ayer que su \u00d3rgano Interno de Control (OIC) investigar\u00eda el asunto.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.proceso.com.mx\/nacional\/2024\/12\/10\/martin-borrego-renuncia-tras-escandalo-por-boda-en-el-munal-341827.html\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El exfuncionario utiliz\u00f3 su cargo en la Canciller\u00eda para pedir el espacio en el Munal y organizar el presunto aniversario 89 de las relaciones diplom\u00e1ticas entre M\u00e9xico y Rumania, el cual era en realidad en la celebraci\u00f3n de su matrimonio Tomado de Proceso Redacci\u00f3n Martes 10 de diciembre de 2024 CIUDAD DE M\u00c9XICO (apro).-Horas despu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,115],"tags":[],"class_list":["post-21527","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mexico","category-politica"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21527"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21527\/revisions"}],"predecessor-version":[{"id":21529,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21527\/revisions\/21529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21528"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}