{"id":21447,"date":"2024-12-08T21:52:01","date_gmt":"2024-12-09T04:52:01","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=21447"},"modified":"2024-12-08T21:52:05","modified_gmt":"2024-12-09T04:52:05","slug":"segob-envia-800-elementos-de-seguridad-despues-de-salida-de-autodefensas-en-pantelho","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/12\/08\/segob-envia-800-elementos-de-seguridad-despues-de-salida-de-autodefensas-en-pantelho\/","title":{"rendered":"Segob env\u00eda 800 elementos de seguridad despu\u00e9s de salida de autodefensas en Pantelh\u00f3"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Como parte de las acciones de apoyo, se est\u00e1n entregando despensas y consultas m\u00e9dicas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomado de El Imparcial\/EFE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudia Ulloa&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Domingo 8 de diciembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PANTELH\u00d3, Chiapas.- El gobierno federal contin\u00faa con las acciones de apoyo y seguridad en Pantelh\u00f3, Chiapas, con el objetivo de restablecer los servicios de agua y electricidad y evitar enfrentamientos en la regi\u00f3n. Rosa Icela Rodr\u00edguez, secretaria de Gobernaci\u00f3n, inform\u00f3 que por segundo d\u00eda consecutivo se desplegaron m\u00e1s de 800 elementos de seguridad, adem\u00e1s de trabajadores federales y estatales, para atender la situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El municipio hab\u00eda sido tomado por dos grupos contrarios de autodefensa, desde el 2021<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el s\u00e1bado, siguiendo instrucciones de la presidenta Claudia Sheinbaum, comenz\u00f3 el despliegue conjunto con la Secretar\u00eda de la Defensa Nacional (Sedena), la Comisi\u00f3n Federal de Electricidad (CFE) y el gobierno estatal, con el fin de atender directamente a la poblaci\u00f3n de manera pac\u00edfica y sin favorecer a ning\u00fan grupo; hasta el momento no se han registrado incidentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de las acciones de apoyo, se est\u00e1n entregando despensas tanto en plazas p\u00fablicas como puerta a puerta, adem\u00e1s de ofrecer consultas m\u00e9dicas, especialmente a mujeres y ni\u00f1as. La ma\u00f1ana del domingo, la afluencia de familias para recibir estos apoyos aument\u00f3 considerablemente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n en Pantelh\u00f3 ha sido tensa desde 2021, cuando los grupos de El Machete y Los Herrera comenzaron a disputar el control del municipio, lo que ha provocado enfrentamientos y desplazamientos. Tras la toma de la presidencia municipal por parte de las autodefensas de El Machete el 3 de diciembre, la Secretar\u00eda de Seguridad indic\u00f3 que el grupo se retir\u00f3 el s\u00e1bado. El gobierno mexicano hace un llamado a la unidad y la construcci\u00f3n de la paz en la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.elimparcial.com\/mexico\/2024\/12\/09\/segob-envia-800-elementos-de-seguridad-despues-de-salida-de-autodefensas-en-pantelho\">https:\/\/www.elimparcial.com\/mexico\/2024\/12\/09\/segob-envia-800-elementos-de-seguridad-despues-de-salida-de-autodefensas-en-pantelho<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las acciones de apoyo, se est\u00e1n entregando despensas y consultas m\u00e9dicas. Tomado de El Imparcial\/EFE Claudia Ulloa&nbsp; Domingo 8 de diciembre de 2024 PANTELH\u00d3, Chiapas.- El gobierno federal contin\u00faa con las acciones de apoyo y seguridad en Pantelh\u00f3, Chiapas, con el objetivo de restablecer los servicios de agua y electricidad y evitar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,115,113],"tags":[],"class_list":["post-21447","post","type-post","status-publish","format-standard","has-post-thumbnail","category-mexico","category-politica","category-seguridad"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=21447"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21447\/revisions"}],"predecessor-version":[{"id":21449,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/21447\/revisions\/21449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/21448"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=21447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=21447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=21447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}