{"id":15234,"date":"2024-07-14T03:23:00","date_gmt":"2024-07-14T10:23:00","guid":{"rendered":"https:\/\/www.regioncuatronoticias.com\/?p=15234"},"modified":"2024-07-14T03:23:02","modified_gmt":"2024-07-14T10:23:02","slug":"entrega-alcalde-astiazaran-deportivo-eusebio-kino-completamente-rehabilitado","status":"publish","type":"post","link":"https:\/\/www.regioncuatronoticias.com\/index.php\/2024\/07\/14\/entrega-alcalde-astiazaran-deportivo-eusebio-kino-completamente-rehabilitado\/","title":{"rendered":"Entrega Alcalde Astiazar\u00e1n Deportivo Eusebio Kino completamente rehabilitado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La comunidad deportiva de Hermosillo se ver\u00e1 beneficiada con la obra ganadora del Presupuesto CRECES 2023 con 1,750 votos y una inversi\u00f3n de 3.7 millones de pesos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hermosillo, Sonora; 13 de julio, 2024.- El apoyo al deporte continuar\u00e1 como la mejor apuesta por Hermosillo, Antonio Astiazar\u00e1n al entregar la rehabilitaci\u00f3n del Deportivo Eusebio Kino, obra de sector ganadora del Presupuesto CRECES con mil 750 votos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Presidente Municipal salud\u00f3 a la comunidad deportista que diariamente se desarrolla en las instalaciones de la unidad que cuenta con nuevo pasto sint\u00e9tico, rehabilitaci\u00f3n de iluminaci\u00f3n y de cancha de basquetbol, entre otras mejoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo siempre he dicho que en Hermosillo tenemos mucho talento, nos sobra talento aqu\u00ed la H suena muy fuerte y vamos a seguir haciendo que suene m\u00e1s fuerte que nunca\u201d, destac\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha obra a cargo del Consejo Municipal de Concertaci\u00f3n para la Obra P\u00fablica (CMCOP) forma parte de los 66 proyectos electos durante las votaciones del Presupuesto CRECES donde la ciudadan\u00eda eligi\u00f3 las prioridades para su comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAgradecemos al Presidente por rehabilitar el campo que estaba en malas condiciones y que ha mejorado\u201d, agreg\u00f3 Amairani Ram\u00edrez, entrenadora de Club Guerreros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asistieron las regidoras Guadalupe Herrera y Araceli Berrelleza, Armando Labrada, director del Instituto del Deporte de Hermosillo (IDH); Daniel Garc\u00eda Escalante, director de Participaci\u00f3n Ciudadana; C\u00e9sar Rasc\u00f3n, titular de CMCOP; entrenadoras, entrenadores y deportistas de f\u00fatbol y futbol flag.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Detalles de la obra:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Inversi\u00f3n: 3.744 millones de pesos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Cancha de futbol: retiro y suministro de 4967 metros cuadrados de pasto sint\u00e9tico, rehabilitaci\u00f3n de porter\u00edas con red y gradas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Cancha de basquetbol: Pintura acr\u00edlica en 587 metros cuadrados; rehabilitaci\u00f3n de tablero-porter\u00edas y parapeto<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Iluminaci\u00f3n: Se rehabilitaron reflectores<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comunidad deportiva de Hermosillo se ver\u00e1 beneficiada con la obra ganadora del Presupuesto CRECES 2023 con 1,750 votos y una inversi\u00f3n de 3.7 millones de pesos Hermosillo, Sonora; 13 de julio, 2024.- El apoyo al deporte continuar\u00e1 como la mejor apuesta por Hermosillo, Antonio Astiazar\u00e1n al entregar la rehabilitaci\u00f3n del Deportivo Eusebio Kino, obra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[5,8,105],"tags":[],"class_list":["post-15234","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","category-hermosillo","category-principal"],"_links":{"self":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/15234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=15234"}],"version-history":[{"count":1,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/15234\/revisions"}],"predecessor-version":[{"id":15236,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/15234\/revisions\/15236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/15235"}],"wp:attachment":[{"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=15234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=15234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.regioncuatronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=15234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}